{"id":15604,"date":"2021-06-24T16:06:55","date_gmt":"2021-06-24T14:06:55","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=15604"},"modified":"2021-06-24T16:08:16","modified_gmt":"2021-06-24T14:08:16","slug":"gera-und-zwickau-kooperieren-fuer-nachhaltige-mobilitaet","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2021\/06\/24\/gera-und-zwickau-kooperieren-fuer-nachhaltige-mobilitaet\/","title":{"rendered":"GERA UND ZWICKAU KOOPERIEREN F\u00dcR NACHHALTIGE MOBILIT\u00c4T"},"content":{"rendered":"\n<p>Die erste Projektphase von \u201eZ-Move 2025\u201c ist abgeschlossen. Zwickaus Oberb\u00fcrgermeisterin Constance Arndt und Geras Oberb\u00fcrgermeister Julian Vonarb unterzeichneten am 24. Juni 2021 im Rahmen einer Pressekonferenz die Vereinbarung zur Zusammenarbeit im Themengebiet \u201cMobilit\u00e4t der Zukunft\u201d zwischen den beiden St\u00e4dten. Ziel ist es insbesondere, gegenseitig von entsprechenden Aktivit\u00e4ten und aus Projekten zu lernen, um weitere Schritte in Richtung einer nachhaltigen Mobilit\u00e4t zu gehen. Unterst\u00fctzt werden die Kommunen durch zwei wissenschaftliche Partner, die Wests\u00e4chsische Hochschule Zwickau und die Duale Hochschule Gera-Eisenach. Dementsprechend unterschrieben auch Prof. Tobias Teich (WHZ) sowie Prof. Burkhard Utecht (Pr\u00e4sident der Dualen Hochschule Gera-Eisenach) die Kooperationsvereinbarung. Zugleich konnte Maxi Pohlschmidt, Projektmitarbeiterin der Stadt Zwickau, bei dem Pressetermin im Zwickauer ubineum Ergebnisse aus der ersten Phase von \u201eZ-Move 2025\u201c pr\u00e4sentieren.<br>\u00a0<br><strong>Z-Move 2025: \u201eZwickauer Mobilit\u00e4tsmanagement f\u00fcr berufsbedingte Verkehrsbewegungen 2025\u201c<\/strong><br>Im Rahmen des vom Bundesministerium f\u00fcr Bildung und Forschung (BMBF) initiierten Wettbewerbs \u201eMobilit\u00e4tsWerkStadt 2025\u201c hatte Zwickau 2019 das Forschungsprojekt \u201eZwickauer Mobilit\u00e4tsmanagement f\u00fcr berufsbedingte Verkehrsbewegungen 2025\u201c (Z-Move 2025) eingereicht. Mit ihrer Projektskizze konnte sich die Stadt gemeinsam mit 44 weiteren Kommunen gegen mehr als 160 deutschlandweite Wettbewerber durchsetzen. \u201eZ-Move 2025\u201c wird in der ersten Phase mit einer Summe von rund 100&#8217;000 Euro zu 100 % durch das BMBF gef\u00f6rdert.<br>\u00a0<br>Zentraler Bestandteil des Projekts, das seit Juni 2020 bearbeitet wird, war die Internet-Befragung von Pendlern, die im Oktober 2020 durchgef\u00fchrt wurde. Fast 900 Personen beteiligten sich an der Analyse, deren Ergebnisse heute vorgestellt wurden. Erfasst wurden beispielsweise das Mobilit\u00e4tsverhalten von Arbeitnehmern, die Gr\u00fcnde f\u00fcr die Wahl bestimmter Verkehrsmittel oder auch Verbesserungsvorschl\u00e4ge. Die Ergebnisse bilden eine wichtige Grundlage f\u00fcr ein Mobilit\u00e4tskonzept sowie die Planung, Umsetzung und Erprobung spezifischer Ma\u00dfnahmen. Letztere sollen in einer zweiten Phase umgesetzt werden. Zwickau ist zuversichtlich, zu den 14 St\u00e4dten zu geh\u00f6ren, die f\u00fcr diese Fortf\u00fchrung durch den Bund ausgew\u00e4hlt werden.<\/p>\n\n\n\n<p>In dieser Projektphase spielt dann auch die Kooperation mit Gera eine gro\u00dfe Rolle, wie Oberb\u00fcrgermeisterin Constance Arndt betonte: \u201eProjekte wie Z-Move 2025 bieten die M\u00f6glichkeit, sich mit anderen St\u00e4dten zu vernetzen und gemeinsam an der Mobilit\u00e4tswende zu arbeiten. Neben Themen von Z-Move 2025 stehen Inhalte von Projekten wie E-Com oder auch ZED stellvertretend f\u00fcr all die Ma\u00dfnahmen, welche ergriffen werden m\u00fcssen, um auch in Zukunft lebenswerten urbanen Raum f\u00fcr die Bev\u00f6lkerung zu schaffen. Ziel sollte es sein, dass St\u00e4dte deutschlandweit voneinander lernen und sich zusammen weiterentwickeln, denn die Fragen der Zeit k\u00f6nnen wir nicht allein beantworten. Der Vertrag einer Zusammenarbeit zwischen Gera und Zwickau, welchen wir hier heute unterzeichnen, kann als Auftakt eines verstetigten Austauschs zwischen den beiden St\u00e4dten gesehen werden.\u201c<\/p>\n\n\n\n<p><strong>Die Kooperation<\/strong><br>Der regelm\u00e4\u00dfige Austausch zwischen den beiden St\u00e4dten im Rahmen von Projekten soll den Transfer von Ergebnissen gew\u00e4hrleisten, um Bausteine der urbanen Verkehrswende bundesl\u00e4nder\u00fcbergreifend schneller umsetzen zu k\u00f6nnen. Im Rahmen von \u201eZ-Move 2025\u201c stehen dabei konkrete Projektbestandteile im Mittelpunkt. Um die Generalisierbarkeit und Wirkung von Ma\u00dfnahmen zu erh\u00f6hen, wird mit Gera eine Partnerkommune einbezogen, die Interesse zeigt, Aspekte k\u00fcnftig auch angepasst an ihren lokalen Kontext zu \u00fcbernehmen. Somit wird Gera in Projektaktivit\u00e4ten einbezogen und ein steter Austausch, z. B. im Rahmen verschiedener Veranstaltungsformate, findet statt.<\/p>\n\n\n\n<p>Julian Vonarb, Oberb\u00fcrgermeister der Stadt Gera, erkl\u00e4rte dazu: \u201eMein anspruchsvolles Ziel ist es, dass Gera die Mobilit\u00e4t der Zukunft f\u00fcr Deutschland aktiv mitgestaltet: Wie werden wir uns in Zukunft fortbewegen? Welche Bedeutung wird das Auto f\u00fcr uns dabei spielen, im Alltag und auf Reisen? Wie werden St\u00e4dte ihre Verkehrsprobleme l\u00f6sen und wie kann Mobilit\u00e4t auch im l\u00e4ndlichen Bereich gesichert werden? Wir werden dabei unterst\u00fctzen, als Anwenderregion Antworten auf solche und weitere Fragen zur Entwicklung der Mobilit\u00e4t zu liefern. Unser autonomer Kleinbus Emma war erst der Anfang. Mit Zwickau werden weitere wichtige Schritte in die Tat umgesetzt werden.\u201c<\/p>\n\n\n\n<p>Ein entstandenes Netzwerk zwischen den beiden St\u00e4dten sowie der beiden ortsans\u00e4ssigen Hoch- und Fachhochschulen (Wests\u00e4chsische Hochschule Zwickau, Duale Hochschule Gera-Eisenach) st\u00e4rkt den Wirtschaftsraum Ostth\u00fcringen\/Westsachsen und kann bestehende Ungleichgewichte gegen\u00fcber bundesdeutschen Metropolen reduzieren.<\/p>\n\n\n\n<p>Die Pressekonferenz fand im Ubineum statt. Die ehemalige Schwimmhalle wurde zu einem Forschungs- und Transferzentrum entwickelt und ist ein Ort der interdisziplin\u00e4ren Zusammenarbeit von Forschung, Praxis und Kommune. Hier arbeiten die Beteiligten gemeinsam an Aufgabenstellungen rund um das nachhaltige Wohnen und Leben der Zukunft in Zwickau \u2013 so auch im Themenbereich Mobilit\u00e4t.<br>\u00a0<br>QUELLE: STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Die erste Projektphase von \u201eZ-Move 2025\u201c ist abgeschlossen. Zwickaus Oberb\u00fcrgermeisterin Constance Arndt und Geras Oberb\u00fcrgermeister Julian Vonarb unterzeichneten am 24. Juni 2021 im Rahmen einer Pressekonferenz die Vereinbarung zur Zusammenarbeit im Themengebiet \u201cMobilit\u00e4t der Zukunft\u201d <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2021\/06\/24\/gera-und-zwickau-kooperieren-fuer-nachhaltige-mobilitaet\/\" title=\"GERA UND ZWICKAU KOOPERIEREN F\u00dcR NACHHALTIGE MOBILIT\u00c4T\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":15605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-15604","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-lokal"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/15604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=15604"}],"version-history":[{"count":3,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/15604\/revisions"}],"predecessor-version":[{"id":15608,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/15604\/revisions\/15608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/15605"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=15604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=15604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=15604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}