{"id":17510,"date":"2021-12-28T03:42:40","date_gmt":"2021-12-28T02:42:40","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=17510"},"modified":"2021-12-28T03:42:42","modified_gmt":"2021-12-28T02:42:42","slug":"protest-gegen-corona-verordnungen-in-greiz","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2021\/12\/28\/protest-gegen-corona-verordnungen-in-greiz\/","title":{"rendered":"PROTEST GEGEN CORONA-VERORDNUNGEN IN GREIZ"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bis zu rund 250 Personen versammelten sich am, Samstag, den 25. Dezember, im Stadtgebiet von Greiz, um dort gegen die geltenden Corona-Regelungen demonstrativ spazieren zu gehen. Kurz nach 19 Uhr trafen sich die Teilnehmer, darunter auch viele Familien und Kinder, um gemeinsam durch mehrere Stra\u00dfen der Greizer Innenstadt zu laufen. Hierzu f\u00fchrten die Spazierg\u00e4nger vereinzelt Fackeln mit sich und spielten \u00fcber mitgef\u00fchrte Lautsprecher Musik ab. Dabei wurden zum Teil der Sicherheitsabstand nicht eingehalten und keine Masken getragen. Gegen 20 Uhr l\u00f6ste sich die Versammlung, welche zuvor nicht angemeldet war, wieder auf.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Bis zu rund 250 Personen versammelten sich am, Samstag, den 25. Dezember, im Stadtgebiet von Greiz, um dort gegen die geltenden Corona-Regelungen demonstrativ spazieren zu gehen. Kurz nach 19 Uhr trafen sich die Teilnehmer, darunter <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2021\/12\/28\/protest-gegen-corona-verordnungen-in-greiz\/\" title=\"PROTEST GEGEN CORONA-VERORDNUNGEN IN GREIZ\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-17510","post","type-post","status-publish","format-standard","has-post-thumbnail","category-polizeiberichte"],"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/17510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=17510"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/17510\/revisions"}],"predecessor-version":[{"id":17511,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/17510\/revisions\/17511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9353"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=17510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=17510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=17510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}