{"id":18096,"date":"2022-02-17T10:21:00","date_gmt":"2022-02-17T09:21:00","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=18096"},"modified":"2022-02-17T09:58:21","modified_gmt":"2022-02-17T08:58:21","slug":"friedhoefe-und-tierpark-aufgrund-der-wetterprognosen-geschlossen","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2022\/02\/17\/friedhoefe-und-tierpark-aufgrund-der-wetterprognosen-geschlossen\/","title":{"rendered":"FRIEDH\u00d6FE UND TIERPARK AUFGRUND DER WETTERPROGNOSEN GESCHLOSSEN"},"content":{"rendered":"\n<p>Aufgrund der amtlichen Unwetterwarnung des Deutschen Wetterdienstes vor orkanartigen B\u00f6en, die nach der vor\u00fcbergehenden Abschw\u00e4chung am Freitag wieder am Wochenende verbreitet auftreten sollen, sind die Geraer Friedh\u00f6fe ab sofort bis auf Widerruf f\u00fcr Besucher gesperrt. Der Geraer Tierpark bleibt am 17. Februar 2022 ebenfalls geschlossen.<\/p>\n\n\n\n<p>Es handelt sich hierbei um reine Vorsichtsma\u00dfnahmen zur Gefahrenabwehr. Die Sicherheit der \u00d6ffentlichkeit, der Mitarbeitenden und der Tiere hat selbstverst\u00e4ndlich oberste Priorit\u00e4t. Weil der Boden aktuell vielerorts mit Feuchtigkeit ges\u00e4ttigt ist und kein Frost herrscht, k\u00f6nnen durch die starken Winde neben Ast- und Kronenausbr\u00fcchen auch ganze B\u00e4ume umgeworfen werden.<\/p>\n\n\n\n<p>Wann die Friedh\u00f6fe und der Tierpark wieder ge\u00f6ffnet werden k\u00f6nnen, ist noch nicht absch\u00e4tzbar. Um Beachtung der Aush\u00e4nge an den Eing\u00e4ngen der Friedh\u00f6fe wird gebeten.<\/p>\n\n\n\n<p>Au\u00dferdem bittet die Stadt Gera alle B\u00fcrger um \u00e4u\u00dferste Vorsicht im Freien und r\u00e4t davon ab, in den n\u00e4chsten Tagen \u00f6ffentliche Gr\u00fcn- und Erholungsanlagen sowie Spielpl\u00e4tze mit Baumbest\u00e4nden zu betreten. Gleiches gilt f\u00fcr den Stadtwald.<\/p>\n\n\n\n<p>Die Baumpfleger und G\u00e4rtner des Amtes f\u00fcr Stadtgr\u00fcn sind nach dem internen Notfall- und Havarieplan ab Donnerstag, den 17. Februar 2022, 6.30 Uhr in Alarmbereitschaft versetzt. Schadensmeldungen f\u00fcr st\u00e4dtische Fl\u00e4chen richten Sie bitte an das Lagezentrum unter der Rufnummer 0365 8333837.<\/p>\n\n\n\n<p>QUELLE: STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Aufgrund der amtlichen Unwetterwarnung des Deutschen Wetterdienstes vor orkanartigen B\u00f6en, die nach der vor\u00fcbergehenden Abschw\u00e4chung am Freitag wieder am Wochenende verbreitet auftreten sollen, sind die Geraer Friedh\u00f6fe ab sofort bis auf Widerruf f\u00fcr Besucher gesperrt. <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2022\/02\/17\/friedhoefe-und-tierpark-aufgrund-der-wetterprognosen-geschlossen\/\" title=\"FRIEDH\u00d6FE UND TIERPARK AUFGRUND DER WETTERPROGNOSEN GESCHLOSSEN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":1630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":{"0":"post-18096","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kurzmitteilungen"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/18096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=18096"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/18096\/revisions"}],"predecessor-version":[{"id":18097,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/18096\/revisions\/18097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/1630"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=18096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=18096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=18096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}