{"id":19247,"date":"2022-05-25T12:37:34","date_gmt":"2022-05-25T10:37:34","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=19247"},"modified":"2022-05-25T12:45:17","modified_gmt":"2022-05-25T10:45:17","slug":"sorge-vor-erneuter-raupenplage-unbegruendet","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2022\/05\/25\/sorge-vor-erneuter-raupenplage-unbegruendet\/","title":{"rendered":"SORGE VOR ERNEUTER RAUPENPLAGE UNBEGR\u00dcNDET"},"content":{"rendered":"\n<p>Die warmen Fr\u00fchlings- und Fr\u00fchsommertemperaturen haben zu guten Bedingungen f\u00fcr die Entwicklung einiger Insekten gef\u00fchrt. Derzeit erh\u00e4lt die Stadtverwaltung\u00a0vermehrt sorgenvolle B\u00fcrgeranfragen, ob der Eichenprozessionsspinner oder andere gef\u00e4hrliche Arten in unserer Stadt aktiv sind. Die Bef\u00fcrchtungen sind unbegr\u00fcndet, wie Konrad Nickschick, Leiter des Geraer Umweltamtes, wei\u00df:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201eBei den regelm\u00e4\u00dfigen Kontrollen stellte sich bisher wiederholt heraus, dass es sich bei den entdeckten Tieren um die Pfaffenh\u00fctchen-Gespinstmotte handelt. Diese ungef\u00e4hrliche, wei\u00dfe Schmetterlingsraupenart mit schwarzen Punkten findet sich an der namensgebenden Pflanze und spinnt die \u00c4ste und Bl\u00e4tter gro\u00dffl\u00e4chig ein. Sie ist weder f\u00fcr Pflanzen, Tiere oder den Menschen gef\u00e4hrlich.\u201c<\/p><\/blockquote>\n\n\n\n<p>Diese und andere h\u00e4ufig vorkommenden Insektenarten in Gera werden f\u00fcr interessierte B\u00fcrger in einer Zusammenstellung auf der st\u00e4dtischen Webseite beschrieben: <\/p>\n\n\n\n<p><a href=\"https:\/\/www.gera.de\/sixcms\/detail.php?id=239211\">https:\/\/www.gera.de\/sixcms\/detail.php?id=239211<\/a>\u00a0<\/p>\n\n\n\n<p>Gleichzeitig weist Nickschick daraufhin, dass langfristig mit einer h\u00e4ufigeren und st\u00e4rkeren Vermehrung einzelner Insektenarten und Sch\u00e4dlingen wie zum Beispiel dem Schwammspinner zu rechnen ist. \u201eGerade der Klimawandel bietet leider gute Voraussetzungen, dass sich der Sch\u00e4dling je nach j\u00e4hrlichem Witterungsverlauf immer mal wieder massenhaft vermehren wird\u201c, so Nickschick. Insbesondere nach milden Wintern gefolgt von warm-trockenen Fr\u00fchjahrs- und Sommermonaten ist ein erneutes massenhaftes Auftreten der Schwammspinner-Raupe zu erwarten. Daher beobachtet die Stadt Gera gemeinsam mit dem Forstamt Weida das Populationsaufkommen fortlaufend und unter wissenschaftlicher Begleitung. Nur so kann fr\u00fchzeitig auf entsprechende Entwicklungen reagiert werden.<\/p>\n\n\n\n<p>F\u00fcr weitere Fragen stehen die Mitarbeiter des Geraer Umweltamtes zur Verf\u00fcgung. Erreichbar sind sie \u00fcber \u201e<a href=\"mailto:umwelt@gera.de\">umwelt@gera.de<\/a>\u201c.<\/p>\n\n\n\n<p><strong>Hintergrundinformation<\/strong><\/p>\n\n\n\n<p>Im Fr\u00fchjahr 2019 erlebten einige Ortsteile Geras ein hohes Raupenaufkommen: Der Schwammspinner, ein in Deutschland nat\u00fcrlich vorkommender Schmetterling, vermehrte sich massenweise. Tausende der haarigen Raupen fra\u00dfen sich durch die W\u00e4lder und Privatg\u00e4rten in Liebschwitz, Taubenpreskeln, Lietzsch, Naulitz, Zw\u00f6tzen, Kaimberg und Poris-Lengefeld und hinterlie\u00dfen in Teilen kahle B\u00e4ume und Gew\u00e4chse. Auch der Raum Heldburg in S\u00fcdth\u00fcringen, Finsterbergen in Mittelth\u00fcringen und Sondershausen in Nordth\u00fcringen sowie Bereiche in Bayern und Sachsen waren betroffen. Im Folgejahr konnten Bev\u00f6lkerung und Wald vor einer erneuten Plage durch das gemeinschaftliche Absammeln der Schwammspinner-Gelege in Liebschwitz mit rund 500 Freiwilligen und durch den gezielten Einsatz des Pflanzenschutzmittels \u201eMimic\u201c in Liebschwitz und Naulitz gesch\u00fctzt werden. Vorsorglich hatte die Stadt zudem Spezialsauger angeschafft und eine Kampagne zur umfassenden Aufkl\u00e4rung der B\u00fcrger durchgef\u00fchrt.<\/p>\n\n\n\n<p>QUELLE: STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Die warmen Fr\u00fchlings- und Fr\u00fchsommertemperaturen haben zu guten Bedingungen f\u00fcr die Entwicklung einiger Insekten gef\u00fchrt. Derzeit erh\u00e4lt die Stadtverwaltung\u00a0vermehrt sorgenvolle B\u00fcrgeranfragen, ob der Eichenprozessionsspinner oder andere gef\u00e4hrliche Arten in unserer Stadt aktiv sind. Die Bef\u00fcrchtungen <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2022\/05\/25\/sorge-vor-erneuter-raupenplage-unbegruendet\/\" title=\"SORGE VOR ERNEUTER RAUPENPLAGE UNBEGR\u00dcNDET\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":19249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-19247","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-lokal"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/19247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=19247"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/19247\/revisions"}],"predecessor-version":[{"id":19250,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/19247\/revisions\/19250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/19249"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=19247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=19247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=19247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}