{"id":19251,"date":"2022-05-26T12:01:27","date_gmt":"2022-05-26T10:01:27","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=19251"},"modified":"2022-05-26T12:01:29","modified_gmt":"2022-05-26T10:01:29","slug":"gruendung-des-energie-wasserstoff-netzwerkes-gera","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2022\/05\/26\/gruendung-des-energie-wasserstoff-netzwerkes-gera\/","title":{"rendered":"GR\u00dcNDUNG DES ENERGIE-WASSERSTOFF-NETZWERKES GERA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Stadt Gera lud in der vergangenen Woche Vertreter des Th\u00fcringer Ministeriums f\u00fcr Umwelt, Energie und Naturschutz, der Industrie- und Handelskammer Ostth\u00fcringen zu Gera, der Handwerkskammer f\u00fcr Ostth\u00fcringen, der Energieversorgung Gera, der Dualen Hochschule Gera-Eisenach sowie von B\u00fcrgerinitiativen ein, um einen gemeinschaftlichen Wissensaustausch \u00fcber erneuerbare Energien zu erm\u00f6glichen. Daraus ging im Rahmen des Projektes Smartcity Gera die Gr\u00fcndung des Energie-Wasserstoff-Netzwerkes Gera hervor. Rico Trost, Leiter des Amtes f\u00fcr Zentrale Steuerung und verantwortlich f\u00fcr das Smartcity-Projekt, erl\u00e4utert:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201eDie Idee ist einfach erkl\u00e4rt. Es gibt innerhalb der Stadt bereits eine Reihe erfolgreicher Nutzungskonzepte und Projekte, in denen erneuerbare Energien wie Wasserstoff oder Photovoltaik eingesetzt werden. Unser Ansatz ist es, sich gegenseitig zu unterst\u00fctzen und diese Expertise geb\u00fcndelt Interessierten der Stadt zug\u00e4nglich zu machen, angefangen von B\u00fcrgerinnen und B\u00fcrgern \u00fcber Vereine bis hin zu Unternehmen.\u201c<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">In regelm\u00e4\u00dfigen Treffen werde sich fortan \u00fcber Technologieentwicklungen ausgetauscht, lokale Firmen in Anwenderfragen unterst\u00fctzt sowie st\u00e4dtische Energieprojekte bei der Realisierung begleitet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Hauptaufgabe des Netzwerkes ist auch das Informieren der interessierten \u00d6ffentlichkeit \u00fcber das Thema Erneuerbare Energien im Allgemeinen und Wasserstoff im Speziellen. Im Herbst 2022 ist daher die erste Veranstaltung des Netzwerkes geplant. Rico Trost formuliert die Zielvorstellung wie folgt:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201eNeben Fachvortr\u00e4gen ist f\u00fcr uns an diesem Tag besonders wichtig, mit der Bev\u00f6lkerung in den Dialog zu treten. Wir wollen wissen: Was sind die W\u00fcnsche und Vorstellungen rund um das Thema Energie? Wo sind Ber\u00fchrungs\u00e4ngste und was bereitet mitunter Sorgen?\u201c<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">QUELLE: STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Die Stadt Gera lud in der vergangenen Woche Vertreter des Th\u00fcringer Ministeriums f\u00fcr Umwelt, Energie und Naturschutz, der Industrie- und Handelskammer Ostth\u00fcringen zu Gera, der Handwerkskammer f\u00fcr Ostth\u00fcringen, der Energieversorgung Gera, der Dualen Hochschule Gera-Eisenach <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2022\/05\/26\/gruendung-des-energie-wasserstoff-netzwerkes-gera\/\" title=\"GR\u00dcNDUNG DES ENERGIE-WASSERSTOFF-NETZWERKES GERA\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":19252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-19251","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lokal"],"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/19251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=19251"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/19251\/revisions"}],"predecessor-version":[{"id":19253,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/19251\/revisions\/19253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/19252"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=19251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=19251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=19251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}