{"id":1969,"date":"2017-09-26T18:32:03","date_gmt":"2017-09-26T16:32:03","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=1969"},"modified":"2017-09-26T18:32:03","modified_gmt":"2017-09-26T16:32:03","slug":"daeumelinchen-in-der-musikschule","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2017\/09\/26\/daeumelinchen-in-der-musikschule\/","title":{"rendered":"D\u00c4UMELINCHEN IN DER MUSIKSCHULE"},"content":{"rendered":"<p>In der Musikschule \u201eHeinrich Sch\u00fctz\u201c landete am Samstag das \u201eD\u00e4umelinchen\u201c mit ihrem dicken Maik\u00e4ferflugobjekt. Die Kinder und alle junggebliebenen Zuschauer lie\u00dfen sich gern mitnehmen zu potentiellen Ehegatten und in das Land der Feen und Elfen.<\/p>\n<p>Alle Zuschauer, die der Einladung des F\u00f6rdervereins der Musikschule \u201eHeinrich Sch\u00fctz\u201c gefolgt waren, sahen eine liebevoll fr\u00f6hliche Interpretation des M\u00e4rchens nach Hans Christian Andersen.<br \/>\nDie Schauspielerin Sandy Sanne als bezauberndes D\u00e4umelinchen, welches sich blitzschnell und mit Leichtigkeit in die weiteren Protagonisten des M\u00e4rchens verwandelte, \u00fcberzeugte durch ihre wunder- und wandelbare Stimme sowie Gestus und Charakter. Sprachgewandt und mit Wortwitz zog sie gleicherma\u00dfen Klein und Gro\u00df in ihren Bann.<\/p>\n<p>Vom imkernd, musizierenden Landwirt, Alexander Weber nicht nur<br \/>\nmit Violine und Posaune unterst\u00fctzt, wurde die Geschichte gleichsam eingeh\u00fcllt. Aus etwas Entfernung begleitet er seine zuk\u00fcnftige Braut durch die gesamte Geschichte, um dann im H\u00f6hepunkt des Geschehens als Elfenk\u00f6nig hervorzutreten und sein D\u00e4umelinchen nach Haus zu f\u00fchren.<\/p>\n<p>Die Theaterimkerei bot Schauspiel und Musik zum Anfassen und wurde f\u00fcr diese feine Theaterarbeit mit reichlich Applaus belohnt. Im Anschluss bot sich die Gelegenheit, die \u201eMitspieler\u201c &#8211; Froschmama nebst Sohn, Feldmaus, Hamster und das Maik\u00e4ferflugobjekt noch aus der N\u00e4he zu bestaunen.<\/p>\n<p>(BILD UND TEXT: MUSIKSCHULE HEINRICH SCH\u00dcTZ)<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>In der Musikschule \u201eHeinrich Sch\u00fctz\u201c landete am Samstag das \u201eD\u00e4umelinchen\u201c mit ihrem dicken Maik\u00e4ferflugobjekt. Die Kinder und alle junggebliebenen Zuschauer lie\u00dfen sich gern mitnehmen zu potentiellen Ehegatten und in das Land der Feen und Elfen. <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2017\/09\/26\/daeumelinchen-in-der-musikschule\/\" title=\"D\u00c4UMELINCHEN IN DER MUSIKSCHULE\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":1970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-1969","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kultur"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/1969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=1969"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/1969\/revisions"}],"predecessor-version":[{"id":1971,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/1969\/revisions\/1971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/1970"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=1969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=1969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=1969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}