{"id":23757,"date":"2023-03-17T12:27:58","date_gmt":"2023-03-17T11:27:58","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=23757"},"modified":"2023-03-17T12:27:59","modified_gmt":"2023-03-17T11:27:59","slug":"sachbeschaedigung-in-der-trebnitzer-strasse","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/03\/17\/sachbeschaedigung-in-der-trebnitzer-strasse\/","title":{"rendered":"SACHBESCH\u00c4DIGUNG IN DER TREBNITZER STRASSE"},"content":{"rendered":"\n<p>Ein 20 Jahre alter Mann muss seit dem 16. M\u00e4rz mit einer Anzeige wegen Sachbesch\u00e4digung rechnen. In der Fr\u00fche gegen 5.30 Uhr besch\u00e4digte er aus noch ungekl\u00e4rter Ursache an seiner Wohnanschrift in der Trebnitzer Stra\u00dfe einen Spiegel sowie die Scheibe im Empfangsbereich der Unterkunft. Da er sich bei seiner Tat leicht verletzte, brachte ihn ein Rettungswagen ins Krankenhaus. Weil der unter Drogen und Alkoholeinfluss stehenden 20-J\u00e4hrige zudem aggressiv auftrat, wurde er polizeilich begleitet. Nach der medizinischen Versorgung konnte er wieder seiner Wege gehen. Ein entsprechendes Verfahren wurde eingeleitet.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Ein 20 Jahre alter Mann muss seit dem 16. M\u00e4rz mit einer Anzeige wegen Sachbesch\u00e4digung rechnen. In der Fr\u00fche gegen 5.30 Uhr besch\u00e4digte er aus noch ungekl\u00e4rter Ursache an seiner Wohnanschrift in der Trebnitzer Stra\u00dfe <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/03\/17\/sachbeschaedigung-in-der-trebnitzer-strasse\/\" title=\"SACHBESCH\u00c4DIGUNG IN DER TREBNITZER STRASSE\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-23757","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-polizeiberichte"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/23757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=23757"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/23757\/revisions"}],"predecessor-version":[{"id":23758,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/23757\/revisions\/23758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9353"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=23757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=23757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=23757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}