{"id":23759,"date":"2023-03-17T12:30:38","date_gmt":"2023-03-17T11:30:38","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=23759"},"modified":"2023-03-17T12:30:39","modified_gmt":"2023-03-17T11:30:39","slug":"vu-auf-kreuzung-bei-bethenhausen","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/03\/17\/vu-auf-kreuzung-bei-bethenhausen\/","title":{"rendered":"VU AUF KREUZUNG BEI BETHENHAUSEN"},"content":{"rendered":"\n<p>Zum Zusammensto\u00df zwischen einem PKW Audi und einem LKW Daimler kam es am 16. M\u00e4rz kurz nach 15 Uhr am Kreuzungsbereich der L 1081 und L 1079. Konkret kollidierten die beiden Fahrzeuge im Zuge eines Abbiegevorganges am Abzweig Bethenhausen miteinander. Die 31-j\u00e4hrige Fahrerin des Audi wurde bei dem Unfall verletzt und kam in ein Krankenhaus. Aufgrund des Unfalls kam es zu Verkehrseinschr\u00e4nkungen. Desweiteren musste der Audi abgeschleppt werden. Die Geraer Polizei hat die Ermittlungen zum Unfall aufgenommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Zum Zusammensto\u00df zwischen einem PKW Audi und einem LKW Daimler kam es am 16. M\u00e4rz kurz nach 15 Uhr am Kreuzungsbereich der L 1081 und L 1079. Konkret kollidierten die beiden Fahrzeuge im Zuge eines <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/03\/17\/vu-auf-kreuzung-bei-bethenhausen\/\" title=\"VU AUF KREUZUNG BEI BETHENHAUSEN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-23759","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-polizeiberichte"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/23759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=23759"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/23759\/revisions"}],"predecessor-version":[{"id":23760,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/23759\/revisions\/23760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9356"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=23759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=23759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=23759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}