{"id":25667,"date":"2023-06-29T22:45:19","date_gmt":"2023-06-29T20:45:19","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=25667"},"modified":"2023-06-29T22:45:21","modified_gmt":"2023-06-29T20:45:21","slug":"obm-besucht-karl-theodor-liebe-gymnasium","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/06\/29\/obm-besucht-karl-theodor-liebe-gymnasium\/","title":{"rendered":"OBM BESUCHT KARL-THEODOR-LIEBE-GYMNASIUM"},"content":{"rendered":"\n<p>Im Rahmen eines Klimaschutzprojektes zum \u201eEarth-Day\u201c bzw. zur \u201eEarth-Hour\u201c war Oberb\u00fcrgermeister Julian Vonarb der Einladung der Klasse 7\/2 zum Austausch \u00fcber Umweltthemen gefolgt. Die Sch\u00fclerinnen und Sch\u00fcler des Karl-Theodor-Liebe-Gymnasiums empfingen das Stadtoberhaupt herzlich und nutzten die Gelegenheit, zahlreiche Fragen zu stellen. Dabei waren die Themen vielf\u00e4ltig und reichten von Umweltschutz, \u00fcber den Werdegang des Oberb\u00fcrgermeisters bis hin zu Fragen wie eine Eingemeindung von St\u00e4dten funktioniere. Die zahlreichen spannenden Fragestellungen, beantworte das Stadtoberhaupt geduldig und ausf\u00fchrlich:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eIch freue mich immer, mit der jungen Generation ins Gespr\u00e4ch zu kommen und zu erfahren, welche Themen sie besch\u00e4ftigen. Denn zu zuh\u00f6ren, vor allem auch der n\u00e4chsten Generation, stellt die Weichen f\u00fcr zuk\u00fcnftige Entscheidungen.\u201c<\/p>\n<\/blockquote>\n\n\n\n<p>Einen gelungenen Abschluss des Besuches war das gemeinsame Einpflanzen von zwei Obstb\u00e4umen im Vorgarten des Karl-Theodor-Liebe-Gymnasiums. Das Geld daf\u00fcr sammelte die Klasse in einer Kuchenbasaraktion. Auf Initiative der Klasse 7\/2 m\u00f6chte sich der Oberb\u00fcrgermeister auch zuk\u00fcnftig f\u00fcr den \u201eEarth Day\u201c in Gera engagieren.<\/p>\n\n\n\n<p>QUELLE: STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Im Rahmen eines Klimaschutzprojektes zum \u201eEarth-Day\u201c bzw. zur \u201eEarth-Hour\u201c war Oberb\u00fcrgermeister Julian Vonarb der Einladung der Klasse 7\/2 zum Austausch \u00fcber Umweltthemen gefolgt. Die Sch\u00fclerinnen und Sch\u00fcler des Karl-Theodor-Liebe-Gymnasiums empfingen das Stadtoberhaupt herzlich und nutzten <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/06\/29\/obm-besucht-karl-theodor-liebe-gymnasium\/\" title=\"OBM BESUCHT KARL-THEODOR-LIEBE-GYMNASIUM\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":25668,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-25667","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kultur"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=25667"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25667\/revisions"}],"predecessor-version":[{"id":25669,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25667\/revisions\/25669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/25668"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=25667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=25667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=25667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}