{"id":25670,"date":"2023-06-29T23:09:52","date_gmt":"2023-06-29T21:09:52","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=25670"},"modified":"2023-06-29T23:09:53","modified_gmt":"2023-06-29T21:09:53","slug":"in-den-sommerferien-mit-buechern-auf-fantasiereisen-gehen","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/06\/29\/in-den-sommerferien-mit-buechern-auf-fantasiereisen-gehen\/","title":{"rendered":"IN DEN SOMMERFERIEN MIT B\u00dcCHERN AUF FANTASIEREISEN GEHEN"},"content":{"rendered":"\n<p><em>Mit der \u00dcbergabe der B\u00fccher und Brosch\u00fcren durch Max Lailach von der Sparkasse Gera-Greiz fiel am Mittwoch, den 28. Juni 2023, der Startschuss f\u00fcr das diesj\u00e4hrige Freizeit-Leseprojekt \u201eIch bin eine Leseratte\u201d in der Stadt- und Regionalbibliothek Gera.<\/em><\/p>\n\n\n\n<p>Die Stadt- und Regionalbibliothek Gera beteiligt sich in diesem Jahr wieder an dem Freizeit-Leseprojekt \u201eIch bin eine Leseratte\u201d. Bereits 2008 initiierten die Landesfachstelle f\u00fcr \u00d6ffentliche Bibliotheken in Th\u00fcringen in Zusammenarbeit mit der Gesch\u00e4ftsstelle Hessische Lesef\u00f6rderung und mit der Sparkassen-Kulturstiftung Hessen-Th\u00fcringen, dieses Projekt f\u00fcr Sch\u00fclerinnen und Sch\u00fcler der 3. bis 6. Klassen vor dem Hintergrund, dass Lesen nur dann richtig Spa\u00df macht, wenn hinter dem Lesenden kein schulischer Druck steht. Die Sparkassen-Kulturstiftung Hessen-Th\u00fcringen stellt dabei gemeinsam mit den Sparkassen vor Ort den Bibliotheken das gesamte Lesematerial sowie die Arbeits- und Werbematerialien f\u00fcr das Projekt zur Verf\u00fcgung. Sie verbindet mit der Durchf\u00fchrung des Freizeit-Leseprojekts gleich zwei F\u00f6rderschwerpunkte miteinander: Die St\u00e4rkung der Th\u00fcringer Bibliotheken und die Vermittlung kultureller Werte an Kinder.<\/p>\n\n\n\n<p>Am Mittwoch, den 28. Juni 2023, \u00fcbergab Max Lailach von der Sparkasse Gera-Greiz, die B\u00fccher und Brosch\u00fcren f\u00fcr das diesj\u00e4hrige Projekt an Britta Frohreich, Gruppenleiterin der Kinderbibliothek, und w\u00fcnschte den Viertkl\u00e4sslern der Bergschule, die zum Projektstart in die Kinderbibliothek am Puschkinplatz gekommen waren, viel Spa\u00df beim Lesen. Im Anschluss stellten Britta Frohreich und Anke Kerst, beide t\u00e4tig bei der Kinderbibliothek, den jungen Leseratten die B\u00fccher kurz vor.<\/p>\n\n\n\n<p>Zur Auswahl stehen sechs spannende und interessante Kinder- und Jugendb\u00fccher:<\/p>\n\n\n\n<p>\u201eChaoskr\u00fcmel &amp; Nervens\u00e4ge \u2014 Die H\u00fchner sind los!\u201d von Tiina und Sinikka Nopola ist ein Bestseller aus Skandinavien mit Gute-Laune-Garantie. Erz\u00e4hlt werden witzige Alltagsabenteuer und Familiengeschichten mit Wohlf\u00fchl-Faktor.<\/p>\n\n\n\n<p>Ein Gangster-Abenteuer verspricht \u201eDas Schloss der Smartphone-Waisen\u201d von Salah Naoura. Kalli, Leo, Tara, Bodhi und Bhavani haben ein Problem: Ihr Waisenhaus soll abgerissen werden. Ein gewiefter Plan muss her.<\/p>\n\n\n\n<p>\u201eElli und der Spion der L\u00fcfte\u201d von Karen Owen ist ein Krimi mit genau der richtigen Spannung und einer guten Prise Humor f\u00fcr Kinder denen das Lesen nicht leichtf\u00e4llt.<\/p>\n\n\n\n<p>In \u201eKiosk, Chaos, Canal Grande\u201d von Edgar Rai verbringt Noah die Ferien bei seiner verr\u00fcckten Oma Violetta in Venedig. Die war fr\u00fcher eine ber\u00fchmte Operns\u00e4ngerin, hat aber jetzt einen kleinen Kiosk. Nicht im Traum h\u00e4tte Noah geahnt, welche Abenteuer dort auf ihn warten.<\/p>\n\n\n\n<p>William Sutcliffes Jugendbuch \u201eGr\u00fcner wird\u2019s nicht \u2014 Der Sommer, in dem ich die Welt rettete\u201d erz\u00e4hlt voller Humor und Witz von \u00d6ko-Engagement und Klimaschutz.<\/p>\n\n\n\n<p>Mit \u201eDas gro\u00dfe Buch vom Essen\u201d von Ola Wolda\u0144ska-P\u0142oci\u0144ska steht auch ein aufwendig gestaltetes Sachbuch zur Wahl. Die Lekt\u00fcre vermittelt alles, was man rund ums Essen wissen muss, macht Spa\u00df und vor allem Appetit.<\/p>\n\n\n\n<p>Damit m\u00f6glichst viele Kinder an dem Projekt teilnehmen k\u00f6nnen, gibt es von jedem Buchtitel mehrere Exemplare. Nicht alle sechs B\u00fccher m\u00fcssen gelesen werden und f\u00fcr besonders eifrige Leseratten legt die Bibliothek noch weitere B\u00fccher bereit. Nach dem Lesen ist die Meinung der jungen Leserinnen und Leser gefragt. Dazu liegen in der Bibliothek Brosch\u00fcren aus. In diesen witzig gestalteten Heftchen sind einige Fragen zu beantworten. Wer kreativ werden m\u00f6chte, kann auch mit einem Bild die eigenen Eindr\u00fccke vom Buch wiedergeben.<\/p>\n\n\n\n<p>Die B\u00fccher k\u00f6nnen ab sofort zusammen mit den Heften in der Kinderbibliothek am Puschkinplatz und in der Stadtteilbibliothek Lusan ausgeliehen werden. Das Mitmachen bei diesem Projekt lohnt sich doppelt: In den Sommerferien sorgen die spannenden und lustigen Geschichten f\u00fcr Abwechslung und Unterhaltung \u2014 egal ob beim Sonnenbaden oder an Regentagen. Sp\u00e4ter kann man mit einem bisschen Gl\u00fcck auch noch Preise gewinnen. Unter allen Teilnehmern werden 30 B\u00fcchergutscheine im Wert von jeweils 15 Euro ausgelost.<\/p>\n\n\n\n<p>QUELLE: STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Mit der \u00dcbergabe der B\u00fccher und Brosch\u00fcren durch Max Lailach von der Sparkasse Gera-Greiz fiel am Mittwoch, den 28. Juni 2023, der Startschuss f\u00fcr das diesj\u00e4hrige Freizeit-Leseprojekt \u201eIch bin eine Leseratte\u201d in der Stadt- und <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/06\/29\/in-den-sommerferien-mit-buechern-auf-fantasiereisen-gehen\/\" title=\"IN DEN SOMMERFERIEN MIT B\u00dcCHERN AUF FANTASIEREISEN GEHEN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":25671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-25670","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kultur"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=25670"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25670\/revisions"}],"predecessor-version":[{"id":25672,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25670\/revisions\/25672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/25671"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=25670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=25670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=25670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}