{"id":25676,"date":"2023-06-30T00:07:18","date_gmt":"2023-06-29T22:07:18","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=25676"},"modified":"2023-06-30T00:07:20","modified_gmt":"2023-06-29T22:07:20","slug":"einbruch-in-grossensteiner-apotheke","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/06\/30\/einbruch-in-grossensteiner-apotheke\/","title":{"rendered":"EINBRUCH IN GROSSENSTEINER APOTHEKE"},"content":{"rendered":"\n<p>Mehrere Polizeistreifen fuhren in der Nacht am 29. Juni nach Gro\u00dfenstein, nachdem von dort gegen 3.20 Uhr der Einbruch in eine Apotheke am S\u00fcdrand mitgeteilt worden war. Nach derzeitigen Informationen verschafften sich zwei T\u00e4ter gewaltsam Zugang zum Inneren der Apotheke. Nach nur kurzer Zeit fl\u00fcchteten die Einbrecher und konnten trotz umfangreicher Fahndung nicht gestellt werden. Was sie letztlich konkret gestohlen haben, ist noch nicht abschlie\u00dfend bekannt. Die KPI in Gera hat die Ermittlungen zum Tatgeschehen \u00fcbernommen und sucht dabei nach Zeugen, die Hinweise zu den Fl\u00fcchtigen geben k\u00f6nnen. Beide T\u00e4ter waren zwischen 170 und 180 Zentimeter gro\u00df, 20 bis 25 Jahre alt, schlank und dunkel gekleidet. Die KPI ist unter der Rufnummer 0365 82341465 erreichbar.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Mehrere Polizeistreifen fuhren in der Nacht am 29. Juni nach Gro\u00dfenstein, nachdem von dort gegen 3.20 Uhr der Einbruch in eine Apotheke am S\u00fcdrand mitgeteilt worden war. Nach derzeitigen Informationen verschafften sich zwei T\u00e4ter gewaltsam <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/06\/30\/einbruch-in-grossensteiner-apotheke\/\" title=\"EINBRUCH IN GROSSENSTEINER APOTHEKE\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-25676","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-polizeiberichte"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=25676"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25676\/revisions"}],"predecessor-version":[{"id":25677,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25676\/revisions\/25677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9351"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=25676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=25676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=25676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}