{"id":25751,"date":"2023-07-03T14:51:51","date_gmt":"2023-07-03T12:51:51","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=25751"},"modified":"2023-07-03T14:51:52","modified_gmt":"2023-07-03T12:51:52","slug":"19-jaehriger-versteckt-sich-hinter-pkw","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/07\/03\/19-jaehriger-versteckt-sich-hinter-pkw\/","title":{"rendered":"19-J\u00c4HRIGER VERSTECKT SICH HINTER PKW"},"content":{"rendered":"\n<p>Dass sich scheinbar jemand an einem in der Reichsstra\u00dfe abgestellte Auto zu schaffen machte, meldete ein Zeuge am 2. Juli um 22.40 Uhr der Polizei. Das Fahrzeug, ein PKW Dacia, stand dabei auf einem Supermarktparkplatz. Als die Polizeistreifen vor Ort ankamen, stellten sie einen 19-J\u00e4hrigen fest, der sich hinter einem Fahrzeug versteckte. Offenbar versuchte dieser, sich unberechtigten Zugang zu dem Auto zu verschaffen, was letzten Endes nicht gelang. Ihn erwartet nun ein entsprechendes Ermittlungsverfahren.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Dass sich scheinbar jemand an einem in der Reichsstra\u00dfe abgestellte Auto zu schaffen machte, meldete ein Zeuge am 2. Juli um 22.40 Uhr der Polizei. Das Fahrzeug, ein PKW Dacia, stand dabei auf einem Supermarktparkplatz. <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/07\/03\/19-jaehriger-versteckt-sich-hinter-pkw\/\" title=\"19-J\u00c4HRIGER VERSTECKT SICH HINTER PKW\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-25751","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-polizeiberichte"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=25751"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25751\/revisions"}],"predecessor-version":[{"id":25752,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25751\/revisions\/25752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9356"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=25751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=25751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=25751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}