{"id":25817,"date":"2023-07-06T17:29:14","date_gmt":"2023-07-06T15:29:14","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=25817"},"modified":"2023-07-06T17:29:15","modified_gmt":"2023-07-06T15:29:15","slug":"siziliens-schmucksteine-im-museum-fuer-naturkunde","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/07\/06\/siziliens-schmucksteine-im-museum-fuer-naturkunde\/","title":{"rendered":"SIZILIENS SCHMUCKSTEINE IM MUSEUM F\u00dcR NATURKUNDE"},"content":{"rendered":"\n<p>Vom 6. Juli 2023 bis zum 25. Februar 2024 pr\u00e4sentiert das Museum f\u00fcr Naturkunde in einer Kabinettausstellung Schmucksteine der italienischen Mittelmeerinsel Sizilien. Dortige Vorkommen von ungew\u00f6hnlichem Achat, Jaspis oder farbigem Feuerstein (Flint) sind bereits seit Jahrhunderten bekannt. Sie wurden sogar zur Ausschm\u00fcckung der Grabkapelle der Medici in Florenz eingesetzt. Auch von Pers\u00f6nlichkeiten wie dem Herzog von Sachsen-Meiningen Anton Ullrich (1687-1773) wurden die Schmucksteine Siziliens gesch\u00e4tzt und gesammelt. Durch dessen umfangreiche Schmucksteinsammlung wurden Th\u00fcringer Wissenschaftler in Schleusingen erst in den 1990er Jahren auf die damals mittlerweile vergessenen sizilianischen Vorkommen aufmerksam. Durch Recherchen und Vergleiche mit historischem Material im Naturhistorischen Museum Wien konnten die alten Fundorte ermittelt werden. Zwischen 1996 und 1999 erbrachten mehrere Sammelexpeditionen nach Sizilien, insbesondere in die Umgebung des kleinen Ortes Giuliana, repr\u00e4sentatives Material, das die Wiederentdeckung der verschollen geglaubten Schmucksteinvorkommen auf Sizilien untermauerte.<\/p>\n\n\n\n<p>Die herrlichen und ungew\u00f6hnlichen Farben und Strukturen der auf Sizilien zu findenden Schmucksteine veranlassten auch die Geraer Mineraliensammler Wolfgang Geinitz und Dr. Matthias Schreiter selbst mehrfach nach Sizilien zu reisen, um sich an der Schatzsuche auf Sizilien zu beteiligen. Das Ergebnis dieser Sammelexkursion zu verschiedenen Fundpunkten auf Sizilien waren hunderte Fundst\u00fccke, die ges\u00e4gt, geschliffen und poliert wurden. Erst die fachkundige Bearbeitung der edlen Funde lie\u00df ihre ganze Pracht erstrahlen. Unbearbeitet war ihr Innenleben zwar schon zu erahnen, die \u00dcberraschung war dennoch meist gro\u00df, als der Schnitt einen Blick in etwas gew\u00e4hrte, worauf noch nie zuvor ein Mensch geschaut hatte. Bei den Schmucksteinen von Sizilien handelt es sich um mikrokristalline Quarze wie den gelben und roten Jaspachat, einer Mischung aus Achat und Jaspis, den in nahezu allen Farben auftretenden Feuerstein (Flint), den Jaspis und den Chalcedon. Kaum vorstellbar ist die Vielfalt der m\u00f6glichen Kombinationen, die sich durch Mischung dieser Quarzvariet\u00e4ten ergeben kann.<\/p>\n\n\n\n<p>Die Ausstellung \u201eSchatzinsel im Mittelmeer \u2013 Siziliens Schmucksteine\u201c zeigt die sch\u00f6nsten und typischsten Exemplare aus der Gesamtausbeute der Geraer Sammler Wolfgang Geinitz und Dr. Matthias Schreiter, erg\u00e4nzt durch stattliche Exemplare aus der Sammlung von Ralf Schmidt. Dr. Matthias Schreiter ist auf das Schleifen und Polieren von Schmuck- bzw. Edelsteinen spezialisiert und hatte die Bearbeitung des gesamten Fundmaterials \u00fcbernommen. Dabei waren pro St\u00fcck mehrere Stunden Arbeitszeit, viel Wissen und Erfahrung notwendig. Die Ausstellung informiert \u00fcber die Charakteristik der Schmucksteine von den jeweiligen sizilianischen Fundorten wie auch \u00fcber die geologischen Grundlagen ihrer Entstehung. Die Geschehnisse um ihre Entdeckung und Wiederentdeckung lassen die Besucher teilhaben an der Geschichte einer Schatzsuche im Mittelmeer.<\/p>\n\n\n\n<p>QUELLE: STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Vom 6. Juli 2023 bis zum 25. Februar 2024 pr\u00e4sentiert das Museum f\u00fcr Naturkunde in einer Kabinettausstellung Schmucksteine der italienischen Mittelmeerinsel Sizilien. Dortige Vorkommen von ungew\u00f6hnlichem Achat, Jaspis oder farbigem Feuerstein (Flint) sind bereits seit <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/07\/06\/siziliens-schmucksteine-im-museum-fuer-naturkunde\/\" title=\"SIZILIENS SCHMUCKSTEINE IM MUSEUM F\u00dcR NATURKUNDE\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":25819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-25817","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kultur"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=25817"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25817\/revisions"}],"predecessor-version":[{"id":25818,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/25817\/revisions\/25818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/25819"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=25817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=25817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=25817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}