{"id":26095,"date":"2023-07-24T09:23:47","date_gmt":"2023-07-24T07:23:47","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26095"},"modified":"2023-07-24T09:23:48","modified_gmt":"2023-07-24T07:23:48","slug":"buergersprechstunde-des-petitionsausschusses","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/07\/24\/buergersprechstunde-des-petitionsausschusses\/","title":{"rendered":"B\u00dcRGERSPRECHSTUNDE DES PETITIONSAUSSCHUSSES"},"content":{"rendered":"\n<p>Der Petitionsausschuss des Th\u00fcringer Landtags bietet regelm\u00e4\u00dfig B\u00fcrgersprechstunden in kreisfreien St\u00e4dten und Landkreisen sowie im Th\u00fcringer Landtag an. Die Sprechstunden werden von Landtagsabgeordneten durchgef\u00fchrt. Die n\u00e4chste B\u00fcrgersprechstunde findet am Dienstag, den 29. August 2023, in der Zeit von 14 Uhr bis 18 Uhr im Raum 118 der Stadtverwaltung, Kornmarkt 12, statt.<\/p>\n\n\n\n<p>Termine f\u00fcr die Sprechstunde k\u00f6nnen telefonisch unter der Rufnummer 0361 3772135 vereinbart werden. Wer nicht die M\u00f6glichkeit hat, den Termin am 29. August 2023 wahrzunehmen, kann sich auch schriftlich an den Th\u00fcringer Landtag, Petitionsausschuss, J\u00fcrgen-Fuchs-Stra\u00dfe 1, 99096 Erfurt, wenden. Petitionen k\u00f6nnen au\u00dferdem auch \u00fcber das Internet auf der Petitionsplattform eingereicht werden:<\/p>\n\n\n\n<p>www.petitionen.thueringer-landtag.de\/<\/p>\n\n\n\n<p>Hintergrund<\/p>\n\n\n\n<p>Nach Artikel 14 der Verfassung des Freistaats Th\u00fcringen hat jede und jeder das Recht, sich mit Bitten und Beschwerden an die Volksvertretung zu wenden. Petitionen k\u00f6nnen in eigener Sache, f\u00fcr andere oder im allgemeinen Interesse eingereicht werden. Der Petitionsausschuss ist zust\u00e4ndig, wenn Eingaben Entscheidungen von Landesbeh\u00f6rden oder anderen Stellen betreffen, die der Aufsicht des Freistaats Th\u00fcringen unterliegen. Der Petitionsausschuss befasst sich beispielsweise mit sozialen Angelegenheiten, Kommunalabgaben, Umweltproblemen, Fragen der \u00f6ffentlichen Ordnung oder baurechtlichen Angelegenheiten. Der Ausschuss nimmt auch Anregungen zur \u00c4nderung von Landesgesetzen entgegen. Privatrechtliche Angelegenheiten wie beispielsweise Mietstreitigkeiten kann der Petitionsausschuss nicht \u00fcberpr\u00fcfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Der Petitionsausschuss des Th\u00fcringer Landtags bietet regelm\u00e4\u00dfig B\u00fcrgersprechstunden in kreisfreien St\u00e4dten und Landkreisen sowie im Th\u00fcringer Landtag an. Die Sprechstunden werden von Landtagsabgeordneten durchgef\u00fchrt. Die n\u00e4chste B\u00fcrgersprechstunde findet am Dienstag, den 29. August 2023, in <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/07\/24\/buergersprechstunde-des-petitionsausschusses\/\" title=\"B\u00dcRGERSPRECHSTUNDE DES PETITIONSAUSSCHUSSES\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":22594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":{"0":"post-26095","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kurzmitteilungen"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26095"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26095\/revisions"}],"predecessor-version":[{"id":26096,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26095\/revisions\/26096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/22594"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}