{"id":26128,"date":"2023-07-25T22:44:25","date_gmt":"2023-07-25T20:44:25","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26128"},"modified":"2023-07-25T22:44:26","modified_gmt":"2023-07-25T20:44:26","slug":"barrieren-und-sorglos-flanierende-fussgaenger","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/07\/25\/barrieren-und-sorglos-flanierende-fussgaenger\/","title":{"rendered":"BARRIEREN UND SORGLOS FLANIERENDE FUSSG\u00c4NGER"},"content":{"rendered":"\n<p>Auf die Ank\u00fcndigung eines B\u00fcrgerdialogs nach der Errichtung der Stra\u00dfensperre am Beginn der Rudolf-Diener-Stra\u00dfe reagierten viele Nutzer dieser Strecke alles andere als erfreut. Warum werden die B\u00fcrger, H\u00e4ndler, Gastronomen und Gewerbetreibende erst befragt, nachdem vollendete Tatsachen geschaffen worden sind? Also vermuteten sie, dass es sich um eine Alibi-Veranstaltung gehandelt hat, und die Meinung der Betroffenen f\u00fcr die Planer im Grunde v\u00f6llig irrelevant ist. Denn die Entwicklungsrichtung stehe doch bereits fest: Die St\u00e4dte sollen langfristig leiser werden, klimaneutral, m\u00f6glichst frei von Autos und Feinstaub, au\u00dferdem viel digitaler als heute.<br><br>Alles lie\u00dfe sich irgendwann bequem ans Bett beordern, und auf der Stra\u00dfe g\u00e4be es, wenn \u00fcberhaupt, nur sorglos flanierende Fu\u00dfg\u00e4nger. Eine Autofahrt w\u00e4re \u00fcberhaupt nicht mehr n\u00f6tig, und irgendwann vielleicht auch gar nicht mehr m\u00f6glich. Ist der schimpfende B\u00fcrger aus Sicht der Stadtplaner also jemand, der alles nur aus seinem Mikrokosmos heraus beurteilt und die gro\u00dfen Zusammenh\u00e4nge nicht versteht? Dann gelten die Barrieren im Grunde genommen den bisherigen, aus diesem Mikrokosmos heraus entstandenen Strukturen, weil sich die Zukunftsvorstellungen von allein nicht durchsetzen w\u00fcrden.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Auf die Ank\u00fcndigung eines B\u00fcrgerdialogs nach der Errichtung der Stra\u00dfensperre am Beginn der Rudolf-Diener-Stra\u00dfe reagierten viele Nutzer dieser Strecke alles andere als erfreut. Warum werden die B\u00fcrger, H\u00e4ndler, Gastronomen und Gewerbetreibende erst befragt, nachdem vollendete <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/07\/25\/barrieren-und-sorglos-flanierende-fussgaenger\/\" title=\"BARRIEREN UND SORGLOS FLANIERENDE FUSSG\u00c4NGER\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":26131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-26128","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-lokal"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26128"}],"version-history":[{"count":2,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26128\/revisions"}],"predecessor-version":[{"id":26132,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26128\/revisions\/26132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/26131"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}