{"id":26161,"date":"2023-07-26T22:28:23","date_gmt":"2023-07-26T20:28:23","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26161"},"modified":"2023-07-26T22:29:11","modified_gmt":"2023-07-26T20:29:11","slug":"einsaetze-der-feuerwehr-11","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/07\/26\/einsaetze-der-feuerwehr-11\/","title":{"rendered":"EINS\u00c4TZE DER FEUERWEHR"},"content":{"rendered":"\n<p>In die Rudolf-Diener-Stra\u00dfe wurden die Fahrzeuge der Freiwilligen Feuerwehr Gera Mitte am 25. Juli um 13 Uhr zu einer Rauchentwicklung aus einem Fenster um 13 Uhr gemeinsam mit den hauptamtlichen Kr\u00e4ften der Wachen 1 und 2, sowie den F\u00fchrungsdiensten der Stufen B und C alarmiert.<br>Beim Eintreffen der ersten Einsatzkr\u00e4fte konnte ein Schwelbrand im Keller festgestellt und abgel\u00f6scht werden. Die Kr\u00e4fte und Mittel reichten an der Einsatzstelle aus, sodass die Freiwillige Feuerwehr Gera-Mitte wieder zur\u00fcck in die Wache konnte.<\/p>\n\n\n\n<p>Gegen 14.30 Uhr am 25. Juli wurde das Hilfeleistungsl\u00f6schfahrzeug der Freiwilligen Feuerwehr Gera Mitte gemeinsam mit den hauptamtlichen Kr\u00e4ften der Wache 2 zu einer Brandmeldeanlage in die Geschwister-Scholl-Stra\u00dfe alarmiert. Der Melder wurde ausfindig gemacht. Es handelte sich um eine Fehlausl\u00f6sung.<\/p>\n\n\n\n<p>Zu einem Rauchwarnmelder mit Rauch aus dem Fenster wurden die Fahrzeuge der Freiwilligen Feuerwehr Gera Mitte am 20. Juli um 16.48 Uhr gemeinsam mit den hauptamtlichen Kr\u00e4ften der Wachen 1 und 2, sowie die F\u00fchrungsdienste der Stufen B und C in die Wiesestra\u00dfe alarmiert. Der Angriffstrupp ging zur Lagerkundung in die Wohnung vor. Angebranntes Essen war die Ursache f\u00fcr die Ausl\u00f6sung des Melders. Die Wohnung wurde bel\u00fcftet.<\/p>\n\n\n\n<p>Im Stadtwald brannte am es 19. Juli im Bereich der Hofer Stra\u00dfe, und am 23. Juli im Bereich Dr.-Semmelweis-Weg. Die Feuer wurden gel\u00f6scht.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>In die Rudolf-Diener-Stra\u00dfe wurden die Fahrzeuge der Freiwilligen Feuerwehr Gera Mitte am 25. Juli um 13 Uhr zu einer Rauchentwicklung aus einem Fenster um 13 Uhr gemeinsam mit den hauptamtlichen Kr\u00e4ften der Wachen 1 und <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/07\/26\/einsaetze-der-feuerwehr-11\/\" title=\"EINS\u00c4TZE DER FEUERWEHR\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":11738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-26161","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-polizeiberichte"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26161"}],"version-history":[{"count":2,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26161\/revisions"}],"predecessor-version":[{"id":26163,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26161\/revisions\/26163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/11738"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}