{"id":26186,"date":"2023-07-28T16:52:47","date_gmt":"2023-07-28T14:52:47","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26186"},"modified":"2023-07-28T16:56:04","modified_gmt":"2023-07-28T14:56:04","slug":"geraer-imam-verstorben","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/07\/28\/geraer-imam-verstorben\/","title":{"rendered":"GERAER IMAM VERSTORBEN"},"content":{"rendered":"\n<p>Der Imam der Moschee am Sachsenplatz ist am 25. Juli 2023 w\u00e4hrend eines Urlaubsaufenthaltes in Nador\/Marokko t\u00f6dlich verungl\u00fcckt. Wie bekannt wurde, handelte es sich um einen Badeunfall im Mittelmeer. Der Vorsteher der muslimischen Gemeinde in Gera hatte sich in einem abgelegenen Strandabschnitt aufgehalten. Die Gemeindemitglieder trauern am Freitag, den 28. Juli 2023. Beigesetzt wird er in Marokko. Er hinterl\u00e4sst eine Familie mit vier Kindern.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Der Imam der Moschee am Sachsenplatz ist am 25. Juli 2023 w\u00e4hrend eines Urlaubsaufenthaltes in Nador\/Marokko t\u00f6dlich verungl\u00fcckt. Wie bekannt wurde, handelte es sich um einen Badeunfall im Mittelmeer. Der Vorsteher der muslimischen Gemeinde in <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/07\/28\/geraer-imam-verstorben\/\" title=\"GERAER IMAM VERSTORBEN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":22617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":{"0":"post-26186","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kurzmitteilungen"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26186"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26186\/revisions"}],"predecessor-version":[{"id":26187,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26186\/revisions\/26187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/22617"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}