{"id":26206,"date":"2023-07-30T14:14:37","date_gmt":"2023-07-30T12:14:37","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26206"},"modified":"2023-07-30T14:14:38","modified_gmt":"2023-07-30T12:14:38","slug":"widerstand-nach-festgestellter-sachbeschaedigung","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/07\/30\/widerstand-nach-festgestellter-sachbeschaedigung\/","title":{"rendered":"WIDERSTAND NACH FESTGESTELLTER SACHBESCH\u00c4DIGUNG"},"content":{"rendered":"\n<p>Im Rahmen der Streifent\u00e4tigkeit stellten Beamte des Inspektionsdienstes am Sonntag, den 30. Juli 2023, um 10.20 Uhr fest, dass eine m\u00e4nnliche Peron einen offensichtlich fremden E-Roller am Museumsplatz durch die Gegend wirft und besch\u00e4digt. Als die Beamten intervenieren wollten, versuchte der T\u00e4ter zu fl\u00fcchten und sich der Identit\u00e4tsfeststellung zu entziehen. Bei seiner Ergreifung leistete er Widerstand gegen die Beamten. Der 43-J\u00e4hrige muss sich nun wegen Sachbesch\u00e4digung und Widerstands verantworten.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Im Rahmen der Streifent\u00e4tigkeit stellten Beamte des Inspektionsdienstes am Sonntag, den 30. Juli 2023, um 10.20 Uhr fest, dass eine m\u00e4nnliche Peron einen offensichtlich fremden E-Roller am Museumsplatz durch die Gegend wirft und besch\u00e4digt. Als <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/07\/30\/widerstand-nach-festgestellter-sachbeschaedigung\/\" title=\"WIDERSTAND NACH FESTGESTELLTER SACHBESCH\u00c4DIGUNG\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":9357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-26206","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-polizeiberichte"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26206"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26206\/revisions"}],"predecessor-version":[{"id":26207,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26206\/revisions\/26207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9357"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}