{"id":26383,"date":"2023-08-13T00:10:00","date_gmt":"2023-08-12T22:10:00","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26383"},"modified":"2023-08-12T22:28:42","modified_gmt":"2023-08-12T20:28:42","slug":"auszeichnungen-zum-internationalen-tag-des-ehrenamtes","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/08\/13\/auszeichnungen-zum-internationalen-tag-des-ehrenamtes\/","title":{"rendered":"AUSZEICHNUNGEN ZUM INTERNATIONALEN TAG DES EHRENAMTES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">J\u00e4hrlich zum 5. Dezember, dem Internationalen Tag des Ehrenamtes, richtet die Stadt Gera eine Festveranstaltung f\u00fcr die b\u00fcrgerschaftlich Engagierten unserer Stadt aus. Als Dank und Wertsch\u00e4tzung f\u00fcr ihren Einsatz erhalten verdiente Ehrenamtliche im Rahmen der Feierlichkeit eine Ehrung durch den Oberb\u00fcrgermeister. Im Rahmen dieser Veranstaltung gilt die Aufmerksamkeit allein denen, die sonst eher abseits der \u00d6ffentlichkeit agieren, sich in ihrer Freizeit ehrenamtlich f\u00fcr andere einsetzen \u2014 egal ob in Vereinen, Stiftungen, sozialen oder \u00f6ffentlichen Einrichtungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ab sofort k\u00f6nnen Vereine, Organisationen oder auch private Initiativen wieder Vorschl\u00e4ge bei der Ehrenamtszentrale der Stadt Gera einreichen. Hierf\u00fcr steht ein Formblatt zur Verf\u00fcgung, dass auf der st\u00e4dtischen Webseite unter \u201ewww.gera.de\u201c heruntergeladen werden kann. Die Vorschlagsfrist endet am 13. Oktober 2023. Der Antrag kann sowohl postalisch an Ehrenamtszentrale, Kornmarkt 7, 07545 Gera als auch \u00fcber \u201eehrenamtszentrale@gera.de\u201c eingereicht werden. Vorgeschlagen werden k\u00f6nnen vollj\u00e4hrige Personen, die mindestens seit f\u00fcnf Jahren ehrenamtlich engagiert sind. Neben den Angaben zur Person, bitten die Organisatoren um eine aussagekr\u00e4ftige Begr\u00fcndung des Vorschlags und um Bild- oder Videomaterial des Ehrenamtlichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere Informationen zum \u201eTag des Ehrenamtes\u201c erhalten Interessierte in der Ehrenamtszentrale oder telefonisch unter der Rufnummer 0365 8381072.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">QUELLE: STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>J\u00e4hrlich zum 5. Dezember, dem Internationalen Tag des Ehrenamtes, richtet die Stadt Gera eine Festveranstaltung f\u00fcr die b\u00fcrgerschaftlich Engagierten unserer Stadt aus. Als Dank und Wertsch\u00e4tzung f\u00fcr ihren Einsatz erhalten verdiente Ehrenamtliche im Rahmen der <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/08\/13\/auszeichnungen-zum-internationalen-tag-des-ehrenamtes\/\" title=\"AUSZEICHNUNGEN ZUM INTERNATIONALEN TAG DES EHRENAMTES\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":22646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-26383","post","type-post","status-publish","format-standard","has-post-thumbnail","category-kurzmitteilungen"],"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26383"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26383\/revisions"}],"predecessor-version":[{"id":26384,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26383\/revisions\/26384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/22646"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}