{"id":26401,"date":"2023-08-14T23:01:31","date_gmt":"2023-08-14T21:01:31","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26401"},"modified":"2023-08-14T23:01:33","modified_gmt":"2023-08-14T21:01:33","slug":"schwerer-vu-auf-dem-stadtring","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/08\/14\/schwerer-vu-auf-dem-stadtring\/","title":{"rendered":"SCHWERER VU AUF DEM STADTRING"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Neben Polizei und Feuerwehr war auch der Rettungsdienst am Sonntag, den 13. August 2023, gegen 10.30 Uhr gefordert. An der Kreuzung Stra\u00dfe des Bergmanns\/Stadtring-S\u00fcd-Ost \u00fcbersah die 37-j\u00e4hrige Renault-Fahrerin, in deren Fahrzeug sich auch eine 39-j\u00e4hrige Frau und zwei f\u00fcnfj\u00e4hrige Jungen befanden, einen vorfahrtsberechtigten Skoda. In diesem sa\u00dfen zwei ein 69-j\u00e4hriger Mann und eine 70-j\u00e4hrige Frau. In Folge der Kollision wurde eines der Fahrzeuge gegen einen in der Ronneburger Stra\u00dfe haltenden VW geschleudert, in welchem sich eine 33-j\u00e4hrige Frau, ein 37-j\u00e4hriger Mann, ein f\u00fcnfj\u00e4hriges M\u00e4dchen, eine 55-j\u00e4hrige Frau und ein 56-j\u00e4hriger Mann befanden. Eine der f\u00fcnf Insassen erlitt hierbei leichte Verletzungen. Im Rahmen der Unfallaufnahme wurden insgesamt sieben Verletzte, vier davon schwer, bilanziert. Zur \u00e4rztlichen Versorgung und dem Transport in Krankenh\u00e4user kamen auch zwei Rettungshubschrauber zum Einsatz. Die Kreuzung war 1 \u00bd Stunden lang vollst\u00e4ndig gesperrt. Es entstand erheblicher Sachschaden. Zur Unfallursache ermittelt die Geraer Polizei.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Neben Polizei und Feuerwehr war auch der Rettungsdienst am Sonntag, den 13. August 2023, gegen 10.30 Uhr gefordert. An der Kreuzung Stra\u00dfe des Bergmanns\/Stadtring-S\u00fcd-Ost \u00fcbersah die 37-j\u00e4hrige Renault-Fahrerin, in deren Fahrzeug sich auch eine 39-j\u00e4hrige <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/08\/14\/schwerer-vu-auf-dem-stadtring\/\" title=\"SCHWERER VU AUF DEM STADTRING\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-26401","post","type-post","status-publish","format-standard","has-post-thumbnail","category-polizeiberichte"],"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26401"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26401\/revisions"}],"predecessor-version":[{"id":26402,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26401\/revisions\/26402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9358"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}