{"id":26406,"date":"2023-08-14T23:07:59","date_gmt":"2023-08-14T21:07:59","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26406"},"modified":"2023-08-14T23:08:01","modified_gmt":"2023-08-14T21:08:01","slug":"mehrere-kellereinbrueche","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/08\/14\/mehrere-kellereinbrueche\/","title":{"rendered":"MEHRERE KELLEREINBR\u00dcCHE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gleich drei Kellerabteile in der Gartenstra\u00dfe gerieten in das Visier von Einbrechern. Die T\u00e4ter \u00f6ffneten diese gewaltsam zwischen dem 9. August 2023 und dem 12. August 2023 und entwendeten ein E-Fahrrad sowie mehrere Flaschen Wein. Mit ihrer Beute ergriffen sie die Flucht, zur\u00fcck blieb Sachschaden. Im gleichen Zeitraum drangen Unbekannte in einen Kellerbereich eines Mehrfamilienhauses in der Kopernikusstra\u00dfe ein. Dort entwendeten sie zwei Fahrr\u00e4der und verursachten ebenso Sachschaden. Die Geraer Polizei hat Ermittlungen zu beiden F\u00e4llen aufgenommen und sucht in diesem Zusammenhang nach Zeugen. Diese d\u00fcrfen sich mit Angabe der Bezugsnummern 0209694\/2023 und 0210234\/2023 unter der Rufnummer 0365 8290 melden.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Gleich drei Kellerabteile in der Gartenstra\u00dfe gerieten in das Visier von Einbrechern. Die T\u00e4ter \u00f6ffneten diese gewaltsam zwischen dem 9. August 2023 und dem 12. August 2023 und entwendeten ein E-Fahrrad sowie mehrere Flaschen Wein. <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/08\/14\/mehrere-kellereinbrueche\/\" title=\"MEHRERE KELLEREINBR\u00dcCHE\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-26406","post","type-post","status-publish","format-standard","has-post-thumbnail","category-polizeiberichte"],"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26406"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26406\/revisions"}],"predecessor-version":[{"id":26407,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26406\/revisions\/26407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9356"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}