{"id":26408,"date":"2023-08-14T23:10:14","date_gmt":"2023-08-14T21:10:14","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26408"},"modified":"2023-08-14T23:10:16","modified_gmt":"2023-08-14T21:10:16","slug":"verfassungswidriges-symbol-in-lkw-geritzt","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/08\/14\/verfassungswidriges-symbol-in-lkw-geritzt\/","title":{"rendered":"VERFASSUNGSWIDRIGES SYMBOL IN LKW GERITZT"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Unbekannte kratzten in der Nacht von Freitag zu Samstag, den 12. August 2023, ein verfassungswidriges Symbol in den Lack eines in der Rudolf-Hundt-Stra\u00dfe geparkten LKW. Die Kriminalpolizei ermittelt nun zu den Hintergr\u00fcnden und bittet Zeugen, sich mit Angabe der Bezugsnummer 0209697\/2023 unter der Telefonnummer 0365 82341465 zu melden.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Unbekannte kratzten in der Nacht von Freitag zu Samstag, den 12. August 2023, ein verfassungswidriges Symbol in den Lack eines in der Rudolf-Hundt-Stra\u00dfe geparkten LKW. Die Kriminalpolizei ermittelt nun zu den Hintergr\u00fcnden und bittet Zeugen, <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/08\/14\/verfassungswidriges-symbol-in-lkw-geritzt\/\" title=\"VERFASSUNGSWIDRIGES SYMBOL IN LKW GERITZT\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-26408","post","type-post","status-publish","format-standard","has-post-thumbnail","category-polizeiberichte"],"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26408"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26408\/revisions"}],"predecessor-version":[{"id":26409,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26408\/revisions\/26409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9351"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}