{"id":26430,"date":"2023-08-16T23:08:02","date_gmt":"2023-08-16T21:08:02","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=26430"},"modified":"2023-08-16T23:08:04","modified_gmt":"2023-08-16T21:08:04","slug":"motorrad-unfall-bei-zossen","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2023\/08\/16\/motorrad-unfall-bei-zossen\/","title":{"rendered":"MOTORRAD-UNFALL BEI ZOSSEN"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Auf der B 92 bei Zossen fuhr am 15. August 2023 gegen 17.10 Uhr ein 53-j\u00e4hriger Motorradfahrer mit seinem Roller Piaggio. Auf nasser Fahrbahn verlor er die Kontrolle \u00fcber das Fahrzeug und schlidderte gegen eine Leitplanke. Hierbei zog er sich mehrere Verletzungen zu. Ein Rettungswagen brachte ihn in ein Krankenhaus, an dem Roller und der Leitplanke entstand Sachschaden. Die Geraer Polizei ermittelt zu der Unfallursache.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Auf der B 92 bei Zossen fuhr am 15. August 2023 gegen 17.10 Uhr ein 53-j\u00e4hriger Motorradfahrer mit seinem Roller Piaggio. Auf nasser Fahrbahn verlor er die Kontrolle \u00fcber das Fahrzeug und schlidderte gegen eine <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2023\/08\/16\/motorrad-unfall-bei-zossen\/\" title=\"MOTORRAD-UNFALL BEI ZOSSEN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-26430","post","type-post","status-publish","format-standard","has-post-thumbnail","category-polizeiberichte"],"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=26430"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26430\/revisions"}],"predecessor-version":[{"id":26431,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/26430\/revisions\/26431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9352"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=26430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=26430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=26430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}