{"id":29196,"date":"2024-01-17T11:12:22","date_gmt":"2024-01-17T10:12:22","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=29196"},"modified":"2024-01-17T11:12:24","modified_gmt":"2024-01-17T10:12:24","slug":"rauchmelder-alarm-in-lusan","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2024\/01\/17\/rauchmelder-alarm-in-lusan\/","title":{"rendered":"RAUCHMELDER-ALARM IN LUSAN"},"content":{"rendered":"\n<p>Alarmschlagende Rauchmelder riefen am 17. Januar kurz nach 2 Uhr nachts Feuerwehr und Polizei auf den Plan. Unverz\u00fcglich r\u00fcckten die Einsatzkr\u00e4fte zum betreffenden Mehrfamilienhaus in die Seydelstra\u00dfe aus. Schnell war die betreffende, leerstehende und unbewohnte Wohnung ausfindig gemacht. Es stellte sich heraus, dass offenbar austretendes Wasser in Kontakt mit einem Sicherungskasten geraten war, und es so zur Rauchentwicklung kam. Die Gefahr wurde folglich beseitigt. Alle Anwohner des Hauses verlie\u00dfen bereits vor Eintreffen der Rettungskr\u00e4fte ihre Wohnungen und konnten am Ende auch wieder dorthin zur\u00fcck. Verletzt wurde zum Gl\u00fcck niemand.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Alarmschlagende Rauchmelder riefen am 17. Januar kurz nach 2 Uhr nachts Feuerwehr und Polizei auf den Plan. Unverz\u00fcglich r\u00fcckten die Einsatzkr\u00e4fte zum betreffenden Mehrfamilienhaus in die Seydelstra\u00dfe aus. Schnell war die betreffende, leerstehende und unbewohnte <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2024\/01\/17\/rauchmelder-alarm-in-lusan\/\" title=\"RAUCHMELDER-ALARM IN LUSAN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":11738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-29196","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-polizeiberichte"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/29196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=29196"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/29196\/revisions"}],"predecessor-version":[{"id":29197,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/29196\/revisions\/29197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/11738"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=29196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=29196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=29196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}