{"id":32101,"date":"2024-06-27T19:21:01","date_gmt":"2024-06-27T17:21:01","guid":{"rendered":"https:\/\/www.studiogera.de\/001\/?p=32101"},"modified":"2024-06-27T19:29:30","modified_gmt":"2024-06-27T17:29:30","slug":"65-tage-vor-der-wahl-in-thueringen","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2024\/06\/27\/65-tage-vor-der-wahl-in-thueringen\/","title":{"rendered":"65 TAGE VOR DER WAHL IN TH\u00dcRINGEN"},"content":{"rendered":"\n<p>Die Umfragewerte f\u00fcr Th\u00fcringen deuten auf eine schwierige Zusammensetzung des k\u00fcnftigen Landesparlamentes hin. Im Auftrag der Funke-Mediengruppe befragte INSA im Zeitraum vom 17. bis 24. Juni 2024 eintausend B\u00fcrger mit folgendem Ergebnis: AFD 29 %, CDU 22 %, BSW 20 %, SPD 7 %, Die Linke 14 %, Gr\u00fcne 4 %, FDP 2 %. Mehrheiten f\u00fcr die Bildung einer Regierung w\u00e4ren bei gleichzeitigem Ausschluss der AFD auch dann nur m\u00f6glich, wenn Parteien mit gegens\u00e4tzlichen Grund\u00fcberzeugungen aufeinander zugehen. Die bisherigen \u00c4u\u00dferungen deuten darauf hin, dass es sich in diesem Falle nur um opportunistische Zweckb\u00fcndnisse oder Verhinderungszusammenschl\u00fcsse handeln k\u00f6nnte.<\/p>\n\n\n\n<p>Gr\u00fcne und FDP werden nach derzeitigem Stand nicht mehr im Landesparlament vertreten sein. Auch die SPD k\u00f6nnte unter die F\u00fcnf-Prozent-H\u00fcrde fallen. Bundespolitische Themen dominieren nach wie vor alle anderen. Eine immer gr\u00f6\u00dfere Rolle spielt die mit der Migration zunehmende Gewalt, welche bislang marginalisiert wurde. Die positiven Erfahrungen mit zugewanderten, gut ausgebildeten Menschen k\u00f6nnen die Bewohner von Plattenbausiedlungen und diversen Wohngegenden nicht teilen. Dort erleben sie sich als Vertreter einer aussterbenden Art, die man nach belieben herabw\u00fcrdigen kann. Auf das Wahlverhalten wirkt sich aus, dass die \u00c4ngste und Bedrohungserfahrungen der immer zahlreicheren Betroffenen h\u00e4ufig unter dem Verdacht des Rechtsextremismus thematisiert werden, was letztendlich tats\u00e4chlich zur Radikalisierung f\u00fchren kann. W\u00e4hrend Gruppen, die der Politik nicht genehm sind, und deren Interessen sie nicht mehr vertreten m\u00f6chte, als Minderheit abgetan werden, finden die Bed\u00fcrfnisse anderer ausgew\u00e4hlter Minderheiten eine besondere, wertsch\u00e4tzende Ber\u00fccksichtigung. Vielen B\u00fcrgern missf\u00e4llt zudem die Aufarbeitung der letzten Wahlniederlagen. Die Verlierer gehen im Grunde davon aus, eine bessere \u00dcberzeugungsarbeit leisten zu m\u00fcssen. Die B\u00fcrger verst\u00fcnden die Zusammenh\u00e4nge nicht, weshalb ihnen die Politik besser erkl\u00e4rt werden m\u00fcsse.<\/p>\n\n\n\n<p>Alles in allem ist mit einem weiteren Auftrieb von AFD und BSW zu rechnen. Denkbar ist, dass die Europawahl-Ergebnisse von Gera den neuen Verh\u00e4ltnissen am n\u00e4chsten kommen. Bei einem AFD-Verbot droht einerseits eine Radikalisierung, andererseits ein schwerwiegender politischer Umbruch, sodass insgesamt eine noch herausfordernde Situation entst\u00fcnde. Vereinfacht dargestellt fangen AFD und BSW eine Mittelschicht auf, die es mit der Fortsetzung der bisherigen Politik, sowohl durch die Transformation als auch durch die Migration, nicht mehr geben w\u00fcrde. Beides k\u00f6nnen die bisher regierenden Parteien nicht mehr r\u00fcckg\u00e4ngig machen. Die CDU kann sich derzeit zwar \u00fcber wachsende Umfragewerte freuen, muss aber damit rechnen, dass sie nach der Landtagswahl, sp\u00e4testens aber nach der Bundestagswahl im September 2025, als eine Art gr\u00fcne Partei mit konservativer Maske angesehen wird und viel Unmut auf sich zieht.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Die Umfragewerte f\u00fcr Th\u00fcringen deuten auf eine schwierige Zusammensetzung des k\u00fcnftigen Landesparlamentes hin. Im Auftrag der Funke-Mediengruppe befragte INSA im Zeitraum vom 17. bis 24. Juni 2024 eintausend B\u00fcrger mit folgendem Ergebnis: AFD 29 %, <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2024\/06\/27\/65-tage-vor-der-wahl-in-thueringen\/\" title=\"65 TAGE VOR DER WAHL IN TH\u00dcRINGEN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":16568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-32101","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-weltweit"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/32101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=32101"}],"version-history":[{"count":5,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/32101\/revisions"}],"predecessor-version":[{"id":32106,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/32101\/revisions\/32106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/16568"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=32101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=32101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=32101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}