{"id":33711,"date":"2024-10-04T11:35:31","date_gmt":"2024-10-04T09:35:31","guid":{"rendered":"https:\/\/www.studiogera.de\/001\/?p=33711"},"modified":"2024-10-06T16:39:28","modified_gmt":"2024-10-06T14:39:28","slug":"bibliothek-plant-neuen-jugendbereich","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2024\/10\/04\/bibliothek-plant-neuen-jugendbereich\/","title":{"rendered":"BIBLIOTHEK PLANT NEUEN JUGENDBEREICH"},"content":{"rendered":"\n<p>Nach \u00fcber 15 Jahren plant die Stadt- und Regionalbibliothek Gera eine Umgestaltung ihres Bereichs f\u00fcr junge Menschen im Alter zwischen 13 und 20 Jahren. Angestrebt wird eine st\u00e4rkere Ausrichtung an den gegenw\u00e4rtigen Bed\u00fcrfnissen und W\u00fcnschen jugendlicher Nutzer. Diese sind nun aufgerufen, sich in dieser \u00a0Neugestaltung mit einzubringen. Mit der Umgestaltung soll langfristig ein Ort geschaffen werden, an dem Jugendliche nicht nur Medien entdecken, sondern auch kreativ arbeiten, lernen und sich mit Gleichgesinnten austauschen k\u00f6nnen. In der Umfrage werden die Jugendlichen nach ihrer Meinung zu Themen wie Raumgestaltung, modernen Medien, Freizeitangeboten und digitalen Dienste gefragt.\u00a0<\/p>\n\n\n\n<p>In einem Projekt mit der Klasse 8 der Entdecker-Gemeinschaftsschule Gera\/Semper Schulen wurde dazu eine Webumfrage entwickelt. Interessierte Jugendliche k\u00f6nnen ab sofort daran teilnehmen:<\/p>\n\n\n\n<p><a href=\"https:\/\/biblio.gera.de\/umfrage-jugendbibliothek\">https:\/\/biblio.gera.de\/umfrage-jugendbibliothek<\/a><\/p>\n\n\n\n<p>Die Umfrage l\u00e4uft bis zum 15. November 2024. Unmittelbar danach werden die Daten ausgewertet und Planungsschritte zur Umgestaltung in einem Konzept festgehalten. Ziel ist es, im kommenden Jahr mit ersten Umsetzungen zu beginnen.<\/p>\n\n\n\n<p>QUELLE: STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Nach \u00fcber 15 Jahren plant die Stadt- und Regionalbibliothek Gera eine Umgestaltung ihres Bereichs f\u00fcr junge Menschen im Alter zwischen 13 und 20 Jahren. Angestrebt wird eine st\u00e4rkere Ausrichtung an den gegenw\u00e4rtigen Bed\u00fcrfnissen und W\u00fcnschen <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2024\/10\/04\/bibliothek-plant-neuen-jugendbereich\/\" title=\"BIBLIOTHEK PLANT NEUEN JUGENDBEREICH\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":33712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-33711","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kultur"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/33711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=33711"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/33711\/revisions"}],"predecessor-version":[{"id":33713,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/33711\/revisions\/33713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/33712"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=33711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=33711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=33711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}