{"id":34100,"date":"2024-10-27T02:00:10","date_gmt":"2024-10-27T01:00:10","guid":{"rendered":"https:\/\/www.studiogera.de\/001\/?p=34100"},"modified":"2024-10-27T02:13:38","modified_gmt":"2024-10-27T01:13:38","slug":"veranstaltungen-am-sonntag-63","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2024\/10\/27\/veranstaltungen-am-sonntag-63\/","title":{"rendered":"VERANSTALTUNGEN AM SONNTAG"},"content":{"rendered":"\n<p>Die Schausteller auf dem Hofwiesenparkplatz laden von 14 Uhr bis 22 Uhr zum Herbstvolksfest ein.<\/p>\n\n\n\n<p>Um 14 Uhr beginnt im Stadtmuseum die letzte \u00f6ffentliche F\u00fchrung durch die Sonderausstellung \u201eGut getroffen! Die Geraer Sch\u00fctzenbilder als Spiegel der Zeit\u201c.<\/p>\n\n\n\n<p>Eine F\u00fchrung durch das Haus Schulenburg wird von 14 Uhr bis 15 Uhr angeboten. Interessierte treffen sich am Eingang Stra\u00dfe des Friedens 120.<\/p>\n\n\n\n<p>Im Stadion am Steg wird um 14 Uhr das Fu\u00dfballspiel BSG Wismut Gera II gegen den VFL Gera angepfiffen.<\/p>\n\n\n\n<p>Die Museumsh\u00f6hler k\u00f6nnen um 11 Uhr, 13 Uhr und 15 Uhr bei einer \u00f6ffentlichen F\u00fchrung erkundet werden. Der Eingang befindet sich auf der R\u00fcckseite des Museums f\u00fcr Naturkunde, Nicolaiberg 3. Das Stadtmuseum zeigt von 11 Uhr bis 17 Uhr historische Sch\u00fctzenbilder und Stadtbilder von Frank Schenke. \u201eB\u00e4ume und Str\u00e4ucher\u201c ist der Titel einer Kabinettausstellung im Museum f\u00fcr Naturkunde, das ebenfalls von 11 Uhr bis 17 Uhr ge\u00f6ffnet ist. Dort k\u00f6nnen in einer weiteren Kabinettausstellung die \u201eGiganten der letzten Eiszeit\u201c bewundert werden. Ge\u00f6ffnet haben auch das Hofwiesenbad und der Tierpark.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Die Schausteller auf dem Hofwiesenparkplatz laden von 14 Uhr bis 22 Uhr zum Herbstvolksfest ein. Um 14 Uhr beginnt im Stadtmuseum die letzte \u00f6ffentliche F\u00fchrung durch die Sonderausstellung \u201eGut getroffen! Die Geraer Sch\u00fctzenbilder als Spiegel <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2024\/10\/27\/veranstaltungen-am-sonntag-63\/\" title=\"VERANSTALTUNGEN AM SONNTAG\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":34101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":{"0":"post-34100","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kurzmitteilungen"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/34100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=34100"}],"version-history":[{"count":3,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/34100\/revisions"}],"predecessor-version":[{"id":34102,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/34100\/revisions\/34102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/34101"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=34100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=34100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=34100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}