{"id":39920,"date":"2025-11-09T09:29:31","date_gmt":"2025-11-09T08:29:31","guid":{"rendered":"https:\/\/www.studiogera.de\/001\/?p=39920"},"modified":"2025-11-09T09:29:33","modified_gmt":"2025-11-09T08:29:33","slug":"missverstaendnis-fuehrt-zu-groesserem-polizeieinsatz","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2025\/11\/09\/missverstaendnis-fuehrt-zu-groesserem-polizeieinsatz\/","title":{"rendered":"MISSVERST\u00c4NDNIS F\u00dcHRT ZU GR\u00d6SSEREM POLIZEIEINSATZ"},"content":{"rendered":"\n<p>Am Samstag, kurz nach 13 Uhr, beobachtete eine 20-j\u00e4hirge Anwohnerin der Kurt-Keicher-Stra\u00dfe durch ihren T\u00fcrspion, wie zwei ihr unbekannte M\u00e4nner versuchten, mit einem gr\u00f6\u00dferen Messer in die Nachbarwohnung einzudringen. Da die Dame der deutschen Sprache nur bedingt m\u00e4chtig war und einen \u00dcberfall vermutete, informierte sie eine Freundin. Die Freundin w\u00e4hlte daraufhin den Notruf. Sofort r\u00fcckten mehrere Streifen des Inspektionsdienstes Gera aus. An bzw. in der betreffenden Wohnung trafen die Beamten auf zwei m\u00e4nnliche Personen. Die Situation konnte schnell entsch\u00e4rft werden. Bei den Herren handelte es sich um die neuen Mieter. Diese hatten sich ausgesperrt und \u00f6ffneten mit einem geliehenen Messer rustikal die T\u00fcr. Da der T\u00fcrrahmen dabei besch\u00e4digt wurde, m\u00fcssen sich die beiden nun wegen Sachbesch\u00e4digung strafrechtlich verantworten.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Am Samstag, kurz nach 13 Uhr, beobachtete eine 20-j\u00e4hirge Anwohnerin der Kurt-Keicher-Stra\u00dfe durch ihren T\u00fcrspion, wie zwei ihr unbekannte M\u00e4nner versuchten, mit einem gr\u00f6\u00dferen Messer in die Nachbarwohnung einzudringen. Da die Dame der deutschen Sprache <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2025\/11\/09\/missverstaendnis-fuehrt-zu-groesserem-polizeieinsatz\/\" title=\"MISSVERST\u00c4NDNIS F\u00dcHRT ZU GR\u00d6SSEREM POLIZEIEINSATZ\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":33265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-39920","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-polizeiberichte"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/39920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=39920"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/39920\/revisions"}],"predecessor-version":[{"id":39921,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/39920\/revisions\/39921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/33265"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=39920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=39920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=39920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}