{"id":40068,"date":"2025-11-17T08:24:32","date_gmt":"2025-11-17T07:24:32","guid":{"rendered":"https:\/\/www.studiogera.de\/001\/?p=40068"},"modified":"2025-11-17T08:24:33","modified_gmt":"2025-11-17T07:24:33","slug":"sitzbaenke-in-brand-gesetzt","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2025\/11\/17\/sitzbaenke-in-brand-gesetzt\/","title":{"rendered":"SITZB\u00c4NKE IN BRAND GESETZT"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Am 16. November 2025 entz\u00fcndete ein bislang unbekannter T\u00e4ter auf dem Hof einer Berufsschule in der Maler-Fischer-Stra\u00dfe die auf dem Grillplatz befindlichen Sitzb\u00e4nke durch Brandlegung. Zudem konnten im Schutt auch Reste eines abgebrannten M\u00fcllcontainers aufgefunden werden. Die Brandursache ist derzeit noch Gegenstand der Ermittlungen. Trotz bisheriger Ermittlungen konnte ein Tatverd\u00e4chtiger nicht identifiziert werden. Die Polizei bittet Zeugen, welche sachdienliche Angaben machen k\u00f6nnen, sich unter der Telefonnummer 0365 8290 zu melden. Es wird um Angabe der Bezugsnummer 0298317\/2025 gebeten.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Am 16. November 2025 entz\u00fcndete ein bislang unbekannter T\u00e4ter auf dem Hof einer Berufsschule in der Maler-Fischer-Stra\u00dfe die auf dem Grillplatz befindlichen Sitzb\u00e4nke durch Brandlegung. Zudem konnten im Schutt auch Reste eines abgebrannten M\u00fcllcontainers aufgefunden <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2025\/11\/17\/sitzbaenke-in-brand-gesetzt\/\" title=\"SITZB\u00c4NKE IN BRAND GESETZT\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":9362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-40068","post","type-post","status-publish","format-standard","has-post-thumbnail","category-polizeiberichte"],"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/40068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=40068"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/40068\/revisions"}],"predecessor-version":[{"id":40069,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/40068\/revisions\/40069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9362"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=40068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=40068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=40068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}