{"id":42514,"date":"2026-05-06T23:29:49","date_gmt":"2026-05-06T21:29:49","guid":{"rendered":"https:\/\/www.studiogera.de\/001\/?p=42514"},"modified":"2026-05-06T23:29:50","modified_gmt":"2026-05-06T21:29:50","slug":"beginn-der-rasenmahd-auf-staedtischen-gruenflaechen","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2026\/05\/06\/beginn-der-rasenmahd-auf-staedtischen-gruenflaechen\/","title":{"rendered":"BEGINN DER RASENMAHD AUF ST\u00c4DTISCHEN GR\u00dcNFL\u00c4CHEN"},"content":{"rendered":"\n<p>Mit dem Einsetzen der Vegetationsperiode hat die Stadt Gera planm\u00e4\u00dfig mit der Rasenmahd auf st\u00e4dtischen Gr\u00fcnfl\u00e4chen begonnen. Insgesamt f\u00fcnf Gruppen des Amtes f\u00fcr Stadtgr\u00fcn sind derzeit im Einsatz und k\u00fcmmern sich um die Pflege von Parkanlagen, Gr\u00fcnfl\u00e4chen sowie Spielpl\u00e4tzen im gesamten Stadtgebiet. Parallel dazu wird bald mit der Mahd von Stra\u00dfenr\u00e4ndern begonnen, um insbesondere die Verkehrssicherheit zu gew\u00e4hrleisten.<\/p>\n\n\n\n<p>Da die zu pflegenden Fl\u00e4chen mit insgesamt rund 266 Hektar die Kapazit\u00e4ten der Stadtverwaltung \u00fcbersteigen, werden erg\u00e4nzend externe Dienstleistungen in Anspruch genommen. Hierf\u00fcr sind vier Firmen beauftragt. Ein Schwerpunkt der Arbeiten liegt dabei in den Stadtteilen Lusan und Debschwitz sowie in den Ortsteilen Westvororte, Zw\u00f6tzen und Langenberg.<\/p>\n\n\n\n<p>Eine besondere Aktion in diesem Jahr ist das gezielte Aussetzen der Mahd auf ausgew\u00e4hlten Fl\u00e4chen im Mai. Diese Vorgehensweise orientiert sich an dem aus Gro\u00dfbritannien stammenden Konzept \u201em\u00e4hfreier Mai\u201c (No Mow May). Ziel ist es, Wildpflanzen eine ungest\u00f6rte Bl\u00fcte zu erm\u00f6glichen und damit die Nahrungsgrundlage f\u00fcr Insekten zu verbessern. Pflanzen wie G\u00e4nsebl\u00fcmchen, Wei\u00dfklee, Margeriten und L\u00f6wenzahn k\u00f6nnen so ausbl\u00fchen und wertvollen Nektar sowie Pollen bereitstellen. Gleichzeitig tr\u00e4gt der h\u00f6here Bewuchs dazu bei, die Austrocknung der B\u00f6den zu verringern und das Bodenleben zu f\u00f6rdern.<\/p>\n\n\n\n<p>Die meisten Fl\u00e4chen, die in diesem Jahr unter dieses naturfreundliche M\u00e4hregime fallen, k\u00f6nnen im Geoportal der Stadt Gera unter dem Thema \u201eGr\u00fcnfl\u00e4chen \u2013 M\u00e4hfreier Mai\u201c eingesehen werden.<\/p>\n\n\n\n<p>Die Stadtverwaltung m\u00f6chte zudem Gartenbesitzer dazu motivieren, im Mai bewusst einzelne Bereiche ihrer G\u00e4rten der Natur zu \u00fcberlassen und auf eine Mahd zu verzichten. So erzielt diese Aktion noch mehr Wirkung und bietet Insekten und Kleinlebewesen wertvollen Lebensraum.<\/p>\n\n\n\n<p>Die Stadtverwaltung bittet um Verst\u00e4ndnis, dass zu Beginn der Vegetationsperiode nicht alle Fl\u00e4chen zeitgleich gem\u00e4ht werden. Gerade in den Monaten April und Mai entwickelt sich die Vegetation besonders dynamisch. Ein Teil der Fl\u00e4chen bleibt daher bewusst l\u00e4nger ungem\u00e4ht \u2013 auch im Sinne des m\u00e4hfreien Mais, der einen wichtigen Beitrag zum Schutz und zur F\u00f6rderung der Artenvielfalt leistet. Vorrang haben weiterhin intensiv genutzte sowie verkehrssicherheitsrelevante Bereiche. Alle \u00fcbrigen Fl\u00e4chen werden im weiteren Verlauf selbstverst\u00e4ndlich ebenfalls gepflegt.<\/p>\n\n\n\n<p>QUELLE:; STADTVERWALTUNG<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Mit dem Einsetzen der Vegetationsperiode hat die Stadt Gera planm\u00e4\u00dfig mit der Rasenmahd auf st\u00e4dtischen Gr\u00fcnfl\u00e4chen begonnen. Insgesamt f\u00fcnf Gruppen des Amtes f\u00fcr Stadtgr\u00fcn sind derzeit im Einsatz und k\u00fcmmern sich um die Pflege von <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2026\/05\/06\/beginn-der-rasenmahd-auf-staedtischen-gruenflaechen\/\" title=\"BEGINN DER RASENMAHD AUF ST\u00c4DTISCHEN GR\u00dcNFL\u00c4CHEN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":42515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-42514","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-lokal"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/42514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=42514"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/42514\/revisions"}],"predecessor-version":[{"id":42516,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/42514\/revisions\/42516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/42515"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=42514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=42514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=42514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}