{"id":44278,"date":"2026-09-02T10:36:21","date_gmt":"2026-09-02T08:36:21","guid":{"rendered":"https:\/\/www.studiogera.de\/001\/?p=44278"},"modified":"2026-09-02T10:36:23","modified_gmt":"2026-09-02T08:36:23","slug":"verletzung-durch-strassenbahnunfall","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2026\/09\/02\/verletzung-durch-strassenbahnunfall\/","title":{"rendered":"VERLETZUNG DURCH STRASSENBAHNUNFALL"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Zu einem Verkehrsunfall mit einem leicht verletzten Jugendlichen kam es am Montag, den 31. August 2026, gegen 13.30 Uhr in der Heinrichstra\u00dfe. Nach bisherigen Erkenntnissen befand sich ein 15-J\u00e4hriger an einer Stra\u00dfenbahnhaltestelle, als er offenbar aufgrund einer Biene erschrak. W\u00e4hrend eine Tram die Haltestelle passierte, geriet der Jugendliche mit einem Bein zwischen Triebwagen und Bahnsteig. Der 15-J\u00e4hrige zog sich hierbei eine leichte Verletzung am Bein zu. Die Polizei nahm den Verkehrsunfall auf und ermittelt unter dem Aktenzeichen 0221652\/20260221652\/2026 zum genauen Unfallhergang.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Zu einem Verkehrsunfall mit einem leicht verletzten Jugendlichen kam es am Montag, den 31. August 2026, gegen 13.30 Uhr in der Heinrichstra\u00dfe. Nach bisherigen Erkenntnissen befand sich ein 15-J\u00e4hriger an einer Stra\u00dfenbahnhaltestelle, als er offenbar <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2026\/09\/02\/verletzung-durch-strassenbahnunfall\/\" title=\"VERLETZUNG DURCH STRASSENBAHNUNFALL\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":15695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-44278","post","type-post","status-publish","format-standard","has-post-thumbnail","category-polizeiberichte"],"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/44278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=44278"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/44278\/revisions"}],"predecessor-version":[{"id":44279,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/44278\/revisions\/44279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/15695"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=44278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=44278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=44278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}