{"id":5904,"date":"2019-01-21T06:01:10","date_gmt":"2019-01-21T05:01:10","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=5904"},"modified":"2019-01-20T21:36:29","modified_gmt":"2019-01-20T20:36:29","slug":"neuer-rtl-podcast-fragen-wir-doch","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2019\/01\/21\/neuer-rtl-podcast-fragen-wir-doch\/","title":{"rendered":"NEUER RTL-PODCAST &#8222;FRAGEN WIR DOCH!&#8220;"},"content":{"rendered":"\n<p>In Berlin wird ein neuer Podcast produziert und jeden Freitag \u00fcber RTL und 105\u20185 Spreeradio ver\u00f6ffentlicht. Unter dem Titel \u201eFragen wir doch!\u201c will man sich mehr Zeit f\u00fcr ausf\u00fchrliche Gespr\u00e4che nehmen und l\u00e4dt prominente G\u00e4ste Politik, Wirtschaft, Unterhaltung und Medien in das Berliner Studio ein. 30 bis 45 Minuten Gespr\u00e4chszeit sind jeweils veranschlagt. Ein erfolgreicher Versuch mit Bundesgesundheitsminister Jens Spahn im vergangenen Jahr hat die RTL Radio Center Berlin GmbH dazu ermuntert, dieses Angebot weiterzuf\u00fchren. Unl\u00e4ngst hatte RTL-Moderator Helmer Litzke den Komiker Bastian Pastewka zu Gast im Berliner Studio. Im H\u00f6rfunk selbst wird dies allerdings nicht gesendet. Der Podcast \u201eFragen wir doch!\u201c wird freitags auf den Seiten www.rtlradio.de, www.spreeradio.de und www.fragenwirdoch.de ver\u00f6ffentlicht, ebenso \u00fcber Apple-Podcasts, Spotify, Soundcloud, Deezer, podcast.de und die Applikationen des Radiosenders RTL. Im RTL-H\u00f6rfunk wird Moderator Helmer Litzke k\u00fcnftig auf H\u00f6hepunkte hinweisen.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>In Berlin wird ein neuer Podcast produziert und jeden Freitag \u00fcber RTL und 105\u20185 Spreeradio ver\u00f6ffentlicht. Unter dem Titel \u201eFragen wir doch!\u201c will man sich mehr Zeit f\u00fcr ausf\u00fchrliche Gespr\u00e4che nehmen und l\u00e4dt prominente G\u00e4ste <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2019\/01\/21\/neuer-rtl-podcast-fragen-wir-doch\/\" title=\"NEUER RTL-PODCAST &#8222;FRAGEN WIR DOCH!&#8220;\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":{"0":"post-5904","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-medien"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/5904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=5904"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/5904\/revisions"}],"predecessor-version":[{"id":5906,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/5904\/revisions\/5906"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=5904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=5904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=5904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}