{"id":6574,"date":"2019-03-19T01:05:11","date_gmt":"2019-03-19T00:05:11","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=6574"},"modified":"2019-03-19T01:05:13","modified_gmt":"2019-03-19T00:05:13","slug":"facebook-will-intensiver-gegen-falschmeldungen-vorgehen","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2019\/03\/19\/facebook-will-intensiver-gegen-falschmeldungen-vorgehen\/","title":{"rendered":"FACEBOOK WILL INTENSIVER GEGEN FALSCHMELDUNGEN VORGEHEN"},"content":{"rendered":"\n<p>Das Unternehmen Facebook meldet, vor der Wahl zum Europ\u00e4ischen Parlament Falschnachrichten noch st\u00e4rker bek\u00e4mpfen zu wollen. Es werde nun ein Zentrum eingerichtet, welches rund um die Uhr mit Ingenieuren, Datenwissenschaftlern, Forschern und Politik-Experten besetzt sei. Man werde mit der Deutschen Presse-Agentur und dem Journalisten-Netzwerk Correctiv zusammenarbeiten und die Authentizit\u00e4t von Ver\u00f6ffentlichungen pr\u00fcfen. Weiterhin wolle man Mitarbeiter von Facebook, die sich an unterschiedlichen Standorten befinden, zusammenschalten und den Kontaktm\u00f6glichkeiten zu nationalen Beh\u00f6rden schaffen.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Das Unternehmen Facebook meldet, vor der Wahl zum Europ\u00e4ischen Parlament Falschnachrichten noch st\u00e4rker bek\u00e4mpfen zu wollen. Es werde nun ein Zentrum eingerichtet, welches rund um die Uhr mit Ingenieuren, Datenwissenschaftlern, Forschern und Politik-Experten besetzt sei. <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2019\/03\/19\/facebook-will-intensiver-gegen-falschmeldungen-vorgehen\/\" title=\"FACEBOOK WILL INTENSIVER GEGEN FALSCHMELDUNGEN VORGEHEN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":4059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":{"0":"post-6574","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-medien"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/6574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=6574"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/6574\/revisions"}],"predecessor-version":[{"id":6575,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/6574\/revisions\/6575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/4059"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=6574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=6574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=6574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}