{"id":9375,"date":"2019-11-19T01:41:38","date_gmt":"2019-11-19T00:41:38","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=9375"},"modified":"2019-11-19T01:44:41","modified_gmt":"2019-11-19T00:44:41","slug":"hwk-praesident-warnt-vor-verlust-handwerklicher-strukturen","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2019\/11\/19\/hwk-praesident-warnt-vor-verlust-handwerklicher-strukturen\/","title":{"rendered":"HWK-PR\u00c4SIDENT WARNT VOR VERLUST HANDWERKLICHER STRUKTUREN"},"content":{"rendered":"\n<p>Einen Verlust handwerklicher Strukturen in besorgniserregendem Ausma\u00df bef\u00fcrchtet der Pr\u00e4sident der Handwerkskammer Ostth\u00fcringen, Klaus N\u00fctzel, f\u00fcr seinen Kammerbezirk. Entsprechend \u00e4u\u00dferte er sich am 16. November 2019 im Kultur- und Kongresszentrum zur Meisterfeier. Als Grund nannte er die verh\u00e4ltnism\u00e4\u00dfig hohe Zahl altersbedingt ausscheidender Firmeninhaber im Vergleich zum Nachwuchs. 1100 bis 1200 Lehrlinge w\u00fcrden j\u00e4hrlich in Ostth\u00fcringen gebraucht, um die Handwerksbetriebe erhalten zu k\u00f6nnen, doch seit zehn Jahren seien es im Schnitt nur 720 pro Jahr. Abitur und Studium w\u00fcrden als erstrebenswerter erachtet als eine Lehre im Handwerk. N\u00fctzel sprach vor rund 500 G\u00e4sten von einem Akademisierungswahn und zunehmender B\u00fcrokratie. Eine L\u00f6sung sieht er unter anderem darin, die in der Automobilindustrie freiwerdenden Besch\u00e4ftigten mit staatlicher Unterst\u00fctzung f\u00fcr das Handwerk umzuschulen. In den Schulen m\u00fcssten bei der Berufsorientierung die Perspektiven im Handwerk besser aufgezeigt werden. Positiv hob er hervor, dass im kommenden Jahr die Meisterpflicht in zw\u00f6lf Gewerken wieder eingef\u00fchrt wird. <\/p>\n\n\n\n<p>Bei der Veranstaltung im Kultur- und Kongresszentrum erhielten 127 Jungmeister aus zw\u00f6lf Gewerken ihre Meisterbriefe, und 17 Betriebswirte ihre Pr\u00fcfungszeugnisse. Die Augenoptiker-Meister bildeten die gr\u00f6\u00dfte Gruppe, die Meister aus dem Gewerk der Maler und Lackierer die kleinste. Den Goldenen Meisterbrief nahmen 27 Altmeister zum 50. Meisterjubil\u00e4um entgegen. 30 Altmeister erhielten zum 60. Meisterjahr eine Jubil\u00e4umsurkunde.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Einen Verlust handwerklicher Strukturen in besorgniserregendem Ausma\u00df bef\u00fcrchtet der Pr\u00e4sident der Handwerkskammer Ostth\u00fcringen, Klaus N\u00fctzel, f\u00fcr seinen Kammerbezirk. Entsprechend \u00e4u\u00dferte er sich am 16. November 2019 im Kultur- und Kongresszentrum zur Meisterfeier. Als Grund nannte <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2019\/11\/19\/hwk-praesident-warnt-vor-verlust-handwerklicher-strukturen\/\" title=\"HWK-PR\u00c4SIDENT WARNT VOR VERLUST HANDWERKLICHER STRUKTUREN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-9375","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-wirtschaft"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=9375"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9375\/revisions"}],"predecessor-version":[{"id":9377,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9375\/revisions\/9377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9379"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=9375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=9375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=9375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}