{"id":9384,"date":"2019-11-20T19:18:24","date_gmt":"2019-11-20T18:18:24","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=9384"},"modified":"2019-11-20T19:18:25","modified_gmt":"2019-11-20T18:18:25","slug":"vortrag-zu-den-geraer-hauszeichen","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2019\/11\/20\/vortrag-zu-den-geraer-hauszeichen\/","title":{"rendered":"VORTRAG ZU DEN GERAER HAUSZEICHEN"},"content":{"rendered":"\n<p>Zur n\u00e4chsten Veranstaltung \u201eGeschichte am Nachmittag\u201c im Stadtmuseum Gera ist Eva-Maria Strau\u00df-Eberhardt zu Gast. Das Thema ihres Vortrages lautet \u201eGeraer Hauszeichen erz\u00e4hlen Stadtgeschichte\u201c.<\/p>\n\n\n\n<p>Lange bevor die Hausnummern in unseren St\u00e4dten \u00fcblich waren, wurden zur Kennzeichnung von H\u00e4usern grafische Ritzsymbole verwendet, die ihren Ursprung in den Steinmetzzeichen hatten. Wappen und Namensk\u00fcrzel als Eigentumszeichen f\u00fcr die Bewohner  des Geb\u00e4udes hatten einen gro\u00dfen Symbolcharakter. Sie waren auch ohne die F\u00e4higkeit des Lesens zu erkennen. Der Vortrag von Eva-Maria Strau\u00df-Eberhardt beginnt im Zentrum und f\u00fchrt die  Besucher \u00fcber die Wiesestra\u00dfe nach Zw\u00f6tzen und weiter nach Lusan. Es ist  erstaunlich, wie viele bemerkenswerte Hauszeichen in Gera bei genauerem Hinsehen zu finden sind. Manche Zeichen wurden nach den Haussanierungen wiederverwendet, andere gingen dagegen f\u00fcr  immer verloren. Der Vortrag startet am 28. November 2019 um 14.00 Uhr im Stadtmuseum Gera.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Zur n\u00e4chsten Veranstaltung \u201eGeschichte am Nachmittag\u201c im Stadtmuseum Gera ist Eva-Maria Strau\u00df-Eberhardt zu Gast. Das Thema ihres Vortrages lautet \u201eGeraer Hauszeichen erz\u00e4hlen Stadtgeschichte\u201c. Lange bevor die Hausnummern in unseren St\u00e4dten \u00fcblich waren, wurden zur Kennzeichnung <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2019\/11\/20\/vortrag-zu-den-geraer-hauszeichen\/\" title=\"VORTRAG ZU DEN GERAER HAUSZEICHEN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":{"0":"post-9384","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kurzmitteilungen"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=9384"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9384\/revisions"}],"predecessor-version":[{"id":9386,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9384\/revisions\/9386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9385"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=9384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=9384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=9384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}