{"id":9709,"date":"2019-12-17T14:10:15","date_gmt":"2019-12-17T13:10:15","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=9709"},"modified":"2019-12-17T14:10:16","modified_gmt":"2019-12-17T13:10:16","slug":"weihnachtsgeschichte-ox-und-esel-im-puppentheater","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2019\/12\/17\/weihnachtsgeschichte-ox-und-esel-im-puppentheater\/","title":{"rendered":"WEIHNACHTSGESCHICHTE \u201eOX UND ESEL\u201d IM PUPPENTHEATER"},"content":{"rendered":"\n<p>Auch in diesem Jahr pr\u00e4sentiert das Theater Altenburg Gera wieder ein neues Puppenspiel zur Weihnachtszeit: \u201eOx und Esel\u201c ist nach der Premiere am 30. November und weiteren Auff\u00fchrungen letztmalig am 25. und 26. Dezember jeweils um 10 Uhr im Puppentheater am Hustav-Hennig-Platz zu sehen.<\/p>\n\n\n\n<p>Die Erz\u00e4hlung von Norbert Ebel f\u00fcr Kinder ab f\u00fcnf Jahren und auch f\u00fcr Erwachsene wirft einen frischen, humorvollen Blick auf die Urspr\u00fcnge der Weihnachtsgeschichte. In einer Art Krippenspiel werden nicht Maria und Joseph, sondern zwei Tiere im Stall zu Eltern. Ein Ochse, genannt Ox, und ein Esel lernen Herausforderungen zu meistern und Verantwortung zu \u00fcbernehmen. Schlie\u00dflich ist es ja unwichtig, wer das Kind gro\u00dfzieht, solange es Liebe und Geborgenheit erf\u00e4hrt. Regie f\u00fchrt dabei Karin Eppler. B\u00fchnenbild und Puppen gestaltet Udo Schneewei\u00df. Als Puppenspielerinnen sind Marcella von Jan und Lys Schubert zu erleben.<\/p>\n\n\n\n<p>Es ist Winter in Bethlehem und eisigkalt. Wie gem\u00fctlich ist es hingegen in dem wohlig warmen Stall, den Ox und Esel gemeinsam bewohnen. Doch die traute Zweisamkeit wird j\u00e4h unterbrochen, als Ox in seiner Futtergrippe ein wimmerndes B\u00fcndel findet \u2013 ein kleines Menschkind und das mitten in seinem k\u00f6stlichen Heu! W\u00e4hrend Ox \u00fcberlegt, wie man das pl\u00e4rrende Baby so schnell wie m\u00f6glich loswerden k\u00f6nnte, hat Esel Mitleid und beginnt, sich im Rahmen seiner M\u00f6glichkeiten um das Kleine zu k\u00fcmmern. Beil\u00e4ufig erz\u00e4hlt er Ox die Weihnachtsgeschichte, wobei ihn sein Erinnerungsverm\u00f6gen ab und an tr\u00fcgt. Schnell wird aus dem Messias ein Matthias und aus der Maria eine Mechthild. Als es pl\u00f6tzlich an der Stallt\u00fcr klopft, werden Esel und Ox selbst zum Teil der Geschichte. Denn jetzt m\u00fcssen sie das Kind vor den Soldaten des Herrn Rodes, oder wie auch immer der hie\u00df, besch\u00fctzen. Und schnell zeigt sich, dass auch dem st\u00f6rrischen Ochsen das kleine Findelkind ans Herz gewachsen ist.<\/p>\n\n\n\n<p>Eintrittskarten sind an der Theaterkasse erh\u00e4ltlich. Diese k\u00f6nnen telefonisch unter der Rufnummer 0365 8279105 bzw. 03447 585177 sowie \u00fcber www.tpthueringen.de reserviert werden.<\/p>\n\n\n\n<p>QUELLE: THEATER ALTENBURG-GERA GGMBH<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Auch in diesem Jahr pr\u00e4sentiert das Theater Altenburg Gera wieder ein neues Puppenspiel zur Weihnachtszeit: \u201eOx und Esel\u201c ist nach der Premiere am 30. November und weiteren Auff\u00fchrungen letztmalig am 25. und 26. Dezember jeweils <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2019\/12\/17\/weihnachtsgeschichte-ox-und-esel-im-puppentheater\/\" title=\"WEIHNACHTSGESCHICHTE \u201eOX UND ESEL\u201d IM PUPPENTHEATER\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-9709","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-theater"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=9709"}],"version-history":[{"count":1,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9709\/revisions"}],"predecessor-version":[{"id":9710,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9709\/revisions\/9710"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=9709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=9709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=9709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}