{"id":9796,"date":"2019-12-25T16:41:06","date_gmt":"2019-12-25T15:41:06","guid":{"rendered":"http:\/\/www.studiogera.de\/001\/?p=9796"},"modified":"2019-12-25T16:41:07","modified_gmt":"2019-12-25T15:41:07","slug":"sechs-neue-strassenbahn-fahrzeuge-sind-moeglich","status":"publish","type":"post","link":"https:\/\/www.studiogera.de\/001\/2019\/12\/25\/sechs-neue-strassenbahn-fahrzeuge-sind-moeglich\/","title":{"rendered":"SECHS NEUE STRASSENBAHN-FAHRZEUGE SIND M\u00d6GLICH"},"content":{"rendered":"\n<p>Der Geraer Verkehrsbetrieb ist bestrebt, die mittlerweile in die Jahre gekommenen Fahrzeuge des tschechischen Herstellers \u010cKD zu ersetzen. Daf\u00fcr seien zw\u00f6lf neue Fahrzeuge notwendig, ggf. auch ein weiteres. Die Kosten w\u00fcrden sich auf 35 Millionen Euro belaufen. Doch wegen der finanziellen Situation k\u00f6nnte sich der GVB dies auch bei einer F\u00f6rderquote von 50 % nicht leisten.<\/p>\n\n\n\n<p>Im Stadtrat wurde am 19. Dezember 2019 ein Kompromiss erzielt, der zumindest den Kauf von voraussichtlich sechs Neufahrzeugen bei einer F\u00f6rderquote von mindestens 50 % erm\u00f6glichen soll. Folgt im April 2020 die Ausschreibung und im Dezember 2020 der Zuschlag, k\u00f6nnten die Fahrzeuge in den Jahren 2021 bis 2023 geliefert werden. Sechs Neufahrzeuge w\u00fcrden zw\u00f6lf \u010cKD-Wagen ersetzen. Dadurch blieben nur noch 15  \u010cKD-Wagen in Betrieb, was bei Doppeltraktionen auf sieben Z\u00fcge und einen Einzelwagen hinauslaufen w\u00fcrde.<\/p>\n\n\n\n<p>Der besagte Kompromiss wurde unter dem Tagesordnungspunkt 8 &#8222;Sicherung des Personennahverkehrs in der Stadt Gera durch eine angemessene Kapitalausstattung der GVB Verkehrs- und Betriebsgesellschaft Gera mbH&#8220; behandelt und hatte 19 F\u00fcr- und 18 Gegenstimmen. B\u00fcndnis &#8217;90\/Die Gr\u00fcnen zogen ihren Antrag dann zur\u00fcck, weil hierf\u00fcr keine Mehrheit erkennbar war. AFD und CDU votierten gegen den Kompromiss.<\/p>\n\n\n\n<p>Demnach soll die Stadt Gera dem GVB ein Teil des Gesellschafterdarlehens \u2014 es hat eine H\u00f6he von 17 Millionen Euro \u2014 erlassen. Nur noch zehn Millionen Euro m\u00fcssen zur\u00fcckgezahlt werden; die nicht mehr r\u00fcckzahlungspflichtigen 6,5 Millionen Euro sollen in Eigenkapital umgewandelt und der Kapitalr\u00fccklage zugef\u00fchrt werden. Zuvor hatten B\u00fcndnis &#8217;90\/Die Gr\u00fcnen den Antrag gestellt, das gesamte Darlehen in Eigenkapital des GVB umzuwandeln. Dagegen wollte die CDU per Antrag eine Stundung des Darlehens bis zum Jahre 2036 erreichen. In dieser Zeit sollten nach Vorstellung der CDU der Bedarf des GVB ermittelt und zun\u00e4chst nur die im Nahverkehrsplan vorgesehenen sechs Neufahrzeuge beschafft werden. Dadurch w\u00fcrden sich die Neubeschaffungen zwar verz\u00f6gern, doch rechnet die CDU in zeitlicher Ferne mit h\u00f6heren F\u00f6rderbetr\u00e4gen.<\/p>\n\n\n\n<p><strong>Hintergrund<\/strong><\/p>\n\n\n\n<p>Die &#8222;Geraer Verkehrsbetrieb GmbH&#8220;, ein Unternehmen der Stadtwerke AG, hatte am 3. Juli 2014 beim Amtsgericht Gera die Er\u00f6ffnung eines Insolvenzverfahrens beantragt. Seit dem 1. Oktober 2016 f\u00fchrt die neugegr\u00fcndete &#8222;GVB Verkehrs- und Betriebsgesellschaft Gera mbH&#8220; den Personennahverkehr in Gera weiter. Diese ist ein Unternehmen der Stadt Gera und wird 20 Jahre lang, bis zur erneuten Ausschreibung der Verkehrsleistung, f\u00fcr den \u00d6PNV verantwortlich sein.<\/p>\n\n\n\n<p>Laut Haushaltsbeschluss vom 24. M\u00e4rz 2016 waren f\u00fcr die &#8222;GVB Verkehrs- und Betriebsgesellschaft Gera mbH&#8220; 29,5 Millionen Euro Eigenkapital vorgesehen. Mit dem Geld wurden die Verm\u00f6genswerte der insolventen &#8222;Geraer Verkehrsbetrieb GmbH&#8220;, insbesondere die Fahrzeuge, zur\u00fcckgekauft und in die neugegr\u00fcndete &#8222;GVB Verkehrs- und Betriebsgesellschaft mbH&#8220; eingebracht. Das Landesverwaltungsamt genehmigte am 8. Juli 2016, dass die Stadtverwaltung hierf\u00fcr einen Kredit aufnehmen darf.<\/p>\n\n\n\n<p>Der Betrag, den die Stadtverwaltung als Kredit aufnahm, die besagten 29,5 Millionen Euro, kam dem Verkehrsbetrieb jedoch nicht gem\u00e4\u00df Haushaltsbeschluss. Auf Veranlassung des B\u00fcrgermeisters wurde die Summe aufgeteilt. Das Unternehmen sollte nun mit nur 12,5 Millionen Euro Eigenkapital ausgestattet werden. Den anderen Teil der Kreditsumme, 17 Millionen Euro, erhielt der Verkehrsbetrieb als Gesellschafterdarlehen \u2014 allerdings ohne Einbindung des Stadtrates. Dieser warf damals dem B\u00fcrgermeister vor, gegen die Th\u00fcringer Kommunalordnung und Beschl\u00fcsse des Stadtrates versto\u00dfen zu haben. Die R\u00fcckzahlung der 17 Millionen Euro sollte in Raten zu 212&#8217;500 Euro je Quartal ab dem IV. 2016 erfolgen. Zwei Raten wurden \u00fcberwiesen, dann folgte am Donnerstag, den 18. Mai 2017, der Beschluss, die Tilgung des Darlehens bis Ende des Jahres 2025 auszusetzen und damit die &#8222;GVB Verkehrs- und Betriebsgesellschaft mbH&#8220; von dieser Last vor\u00fcbergehend zu befreien.<\/p>\n\n\n\n<p>Weiteres zu den in Gera eingesetzten \u010cKD-Wagen finden Sie in unserer Dokumentation:<\/p>\n\n\n\n<p><a href=\"http:\/\/www.studiogera.de\/001_DATEI\/B_102.htm\">Dokument \u201e\u010cKD-Linienfahrzeuge in Gera\u201c<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Der Geraer Verkehrsbetrieb ist bestrebt, die mittlerweile in die Jahre gekommenen Fahrzeuge des tschechischen Herstellers \u010cKD zu ersetzen. Daf\u00fcr seien zw\u00f6lf neue Fahrzeuge notwendig, ggf. auch ein weiteres. Die Kosten w\u00fcrden sich auf 35 Millionen <a class=\"mh-excerpt-more\" href=\"https:\/\/www.studiogera.de\/001\/2019\/12\/25\/sechs-neue-strassenbahn-fahrzeuge-sind-moeglich\/\" title=\"SECHS NEUE STRASSENBAHN-FAHRZEUGE SIND M\u00d6GLICH\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":9802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-9796","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-lokal"},"_links":{"self":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/comments?post=9796"}],"version-history":[{"count":5,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9796\/revisions"}],"predecessor-version":[{"id":9803,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/posts\/9796\/revisions\/9803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media\/9802"}],"wp:attachment":[{"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/media?parent=9796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/categories?post=9796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiogera.de\/001\/wp-json\/wp\/v2\/tags?post=9796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}